{"id":4761,"date":"2022-07-14T12:47:20","date_gmt":"2022-07-14T10:47:20","guid":{"rendered":"https:\/\/robertopla.net\/blog\/politica-de-cookies-ue"},"modified":"2023-03-06T19:36:18","modified_gmt":"2023-03-06T18:36:18","slug":"politica-de-cookies-ue","status":"publish","type":"page","link":"https:\/\/robertopla.net\/blog\/politica-de-cookies-ue","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<p>Esta web no utiliza tecnolog\u00edas como las cookies para almacenar y\/o acceder a la informaci\u00f3n del dispositivo. Este consentimiento se presenta porque nos obliga la ley. Puedes apretar cualquiera de los botones y el resultado ser\u00e1 el mismo: tus datos nos importan un bledo y seguiremos sin almacenarlos ni hacerles ni caso.<\/p>\n<h2>Datos de contacto<\/h2>\n<p>Para preguntas y\/o comentarios sobre nuestra pol\u00edtica de cookies y esta declaraci\u00f3n, por favor, contacta con nosotros usando los siguientes datos:<\/p>\n<p><em>Roberto Pl\u00e0 Aragon\u00e9s<\/em><br \/>\nFigueres, (Girona)<br \/>\nEspa\u00f1a<br \/>\nWeb:\u00a0<a href=\"https:\/\/robertopla.net\/blog\">https:\/\/robertopla.net\/<\/a><br \/>\n<a href=\"http:\/\/robertopla.net\/img\/escribira.jpg\"><img decoding=\"async\" style=\"border:none;width:200px;height:200px\" src=\"http:\/\/robertopla.net\/img\/escribira.jpg\" alt=\"mi correo\" title=\"mi correo\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta web no utiliza tecnolog\u00edas como las cookies para almacenar y\/o acceder a la informaci\u00f3n del dispositivo. Este consentimiento se presenta porque nos obliga la ley. Puedes apretar cualquiera de los botones y el resultado ser\u00e1 el mismo: tus datos &hellip; <a href=\"https:\/\/robertopla.net\/blog\/politica-de-cookies-ue\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4761","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/pages\/4761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=4761"}],"version-history":[{"count":8,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/pages\/4761\/revisions"}],"predecessor-version":[{"id":4847,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/pages\/4761\/revisions\/4847"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=4761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}