{"id":118,"date":"2006-12-28T20:30:47","date_gmt":"2006-12-28T18:30:47","guid":{"rendered":"http:\/\/robertopla.net\/blog\/la-casa-de-los-mapas.htm"},"modified":"2006-12-28T20:30:47","modified_gmt":"2006-12-28T18:30:47","slug":"la-casa-de-los-mapas","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/la-casa-de-los-mapas.htm","title":{"rendered":"La Casa de los Mapas"},"content":{"rendered":"<p>Aun siendo el d\u00eda de los <a href=\"http:\/\/es.wikipedia.org\/wiki\/D%C3%ADa_de_los_Santos_Inocentes\">Santos Inocentes<\/a> me he atrevido a quedar con mi amigo Miguel Puchol porque es una persona seria y en su apretada agenda de auditor de cuentas solo le quedaba esta ma\u00f1ana. De hecho hab\u00edamos hablado en la <a href=\"http:\/\/es.groups.yahoo.com\/group\/ArqueologiaMilitar\/\">lista de correo de Arqueolog\u00eda militar<\/a> que ir\u00edamos a ver <a href=\"http:\/\/maps.google.com\/maps?f=q&#038;hl=es&#038;q=37%C2%B030%2719.41%22N+1%C2%B036%2719.60%22W&#038;ie=UTF8&#038;z=16&#038;ll=37.505811,-1.605442&#038;spn=0.00766,0.021629&#038;t=k&#038;om=1&#038;iwloc=addr\">unas fortificaciones de la guerra civil<\/a> que hab\u00eda descubierto Paco Pepe en la carretera de Aguilas a Mazarr\u00f3n, pero Miguel no pod\u00eda dedicar la ma\u00f1ana a eso y ha prometido compensarme con una interesante visita.<\/p>\n<p>Y realmente ha sido interesante, despu\u00e9s de encontrarnos, darnos un abrazo y disfrutar un ligero almuerzo murciano, me ha llevado a <a href=\"http:\/\/www.fomento.es\/NR\/rdonlyres\/AA13B8CD-2416-45EC-AE7F-AACDA8D1BBA4\/3665\/bol16_p4.pdf\">La Casa del Mapa<\/a>, en la <a href=\"http:\/\/maps.google.com\/maps?f=q&#038;hl=es&#038;ie=UTF8&#038;om=1&#038;z=18&#038;ll=37.984807,-1.126099&#038;spn=0.001903,0.003648&#038;t=k\">Plaza de las Balsas 1<\/a>.<\/p>\n<p>Antes de entrar en materia comentar\u00e9 que Miguel es popularmente conocido entre los amigos como &#8216;<em>Miguelito el de las Bombas<\/em>&#8216;, no por que tenga alma de dinamitero sino por sus <a href=\"http:\/\/aguilasnoticias.com\/index.php?\/colaboradores\/detalle\/17\/1\">conocimientos eruditos<\/a> sobre los bombardeos durante la guerra civil. Miguel tiene algo que yo le envidio profundamente, que es una memoria precisa para todos los detalles y puede recordar un bombardeo citando la fecha, las unidades de las que proced\u00edan los aviones que efectuaron la operaci\u00f3n o los nombres de los tripulantes, los da\u00f1os, los heridos y fallecidos&#8230;algo asombroso para alguien como yo que me cuesta retener todos esos detalles y que de hecho sin mis notas estoy perdido.<\/p>\n<div style=\"text-align:center;\">\n<p><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/puchol.jpg\" border=\"0\" alt=\"Miguel S. Puchol\" title=\"Miguel S. Puchol\" \/><br \/><small>21\/09\/2005. Los Alcazares &#8211; Miguel Puchol, pleno de conocimiento, derrochando datos en pleno trance, durante su inolvidable charla del curso de verano &#8216;La Aviaci\u00f3n en la Guerra Civil&#8217; en cuya organizaci\u00f3n participaba nuestro com\u00fan amigo Marcelino.<\/small><\/p>\n<\/div>\n<p>En el curso de verano sobre la aviaci\u00f3n en la guerra civil en Los Alc\u00e1zares en 2005, nos ofreci\u00f3 una amena e interesant\u00edsima charla en la cual nos comentaba una sucesi\u00f3n de fotograf\u00edas con mil detalles sobre cada una, relacion\u00e1ndolas unas con otras y con las diferentes operaciones de bombardeo con un virtuosismo y un dominio del tema asombroso y admirable.<\/p>\n<p>En mis investigaciones en el archivo italiano del <em>Ufficio Storico<\/em>, su experiencia y su consejo han sido una de las claves del excelente rendimiento que saqu\u00e9 a la visita y despu\u00e9s de aquello hemos hablado de pr\u00e1cticamente formar una &#8216;<em>cooperativa de datos<\/em>&#8216; para &#8216;<em>saquear<\/em>&#8216; -en mejor de los sentidos- toda fuente de datos a nuestro alcance y compartir el bot\u00edn como corsarios al servicio del conocimiento.<\/p>\n<p>Volviendo a la casa de los mapas hay que decir que es un organismo del <a href=\"http:\/\/www.cnig.es\/\">Centro Nacional de Informaci\u00f3n Geogr\u00e1fica<\/a>, dependiente del <a href=\"http:\/\/www.fomento.es\/\">Ministerio de Fomento<\/a> y que b\u00e1sicamente funciona como una biblioteca y como una tienda de mapas, cartas n\u00e1uticas (no vi referencias a cartograf\u00eda aeron\u00e1utica), fotograf\u00eda a\u00e9rea, atlas, mapas en relieve y puzzles y otros objetos relacionados con la geograf\u00eda y la cartograf\u00eda.<\/p>\n<p>Una aut\u00e9ntica cueva de Ali Bab\u00e1 cuajada de tesoros donde pasar interminables horas dejando los ojos en mapas y fotograf\u00edas, un recurso valios\u00edsimo para cualquier investigaci\u00f3n que deba ser georeferenciada, ya que por mucho que <a href=\"http:\/\/earth.google.es\/\">Google Earth<\/a> y <a href=\"http:\/\/www.yourgmap.com\/\">otras herramientas<\/a> disponibles en la red sean una ayuda r\u00e1pida y accesible, al final hay que ir al mapa &#8216;de verdad&#8217; donde se encuentran todos los datos geogr\u00e1ficos. Su auxilio es tan necesario como el del diccionario para el estudiante porque proporciona informaci\u00f3n exacta y completa.<\/p>\n<p>Sin duda alguna mis paseos murcianos me llevar\u00e1n muchas veces m\u00e1s por la calle San Antonio a este bello palacete de la Plaza de las Balsas, tan magn\u00edficamente acondicionado en todos los aspectos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aun siendo el d\u00eda de los Santos Inocentes me he atrevido a quedar con mi amigo Miguel Puchol porque es una persona seria y en su apretada agenda de auditor de cuentas solo le quedaba esta ma\u00f1ana. De hecho hab\u00edamos &hellip; <a href=\"https:\/\/robertopla.net\/blog\/la-casa-de-los-mapas.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-118","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}