{"id":130,"date":"2007-02-12T21:43:11","date_gmt":"2007-02-12T19:43:11","guid":{"rendered":"http:\/\/robertopla.net\/blog\/gris-cielo.htm"},"modified":"2007-02-12T21:43:11","modified_gmt":"2007-02-12T19:43:11","slug":"gris-cielo","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/gris-cielo.htm","title":{"rendered":"Gris cielo"},"content":{"rendered":"<p>Hoy estaba leyendo la <a href=\"http:\/\/www.mde.es\/contenido.jsp?id_nodo=4335&#038;&#038;&#038;keyword=&#038;auditoria=F\">Revista Espa\u00f1ola de Defensa<\/a>. Se trata de la revista del ministerio, \u201cla defensa roja\u201d, as\u00ed conocida por el color de su portada, para diferenciarla de la \u201c<a href=\"http:\/\/defensa.com\/\">defensa negra<\/a>\u201d del  Grupo EDEFA.<\/p>\n<p>Uno de sus art\u00edculos, \u201cPintura de caza\u201d habla sobre las nuevas libreas que se est\u00e1n aplicando a los F-18 y que se espera sean establecidas con car\u00e1cter general para todos los cazas del ej\u00e9rcito del Aire.<\/p>\n<p>En principio se trata de simplificar el esquema de pintura de los F-18 que hasta ahora ven\u00edan luciendo un camuflaje en dos tonos de gris, muy poco diferenciados, el m\u00e1s oscuro en la parte superior y el mas claro en la inferior. Seg\u00fan la maestranza el esquema de dos colores implicaba un notable esfuerzo adicional ya que hay que enmascarar la zona pintada antes de dar el segundo color.<\/p>\n<p>Por otra parte se pintar\u00e1 una falsa cabina en la parte inferior de la misma, tal y como llevan pintado actualmente los F-1 y se espera que este esquema se aplique a todos los aviones de caza espa\u00f1oles, Mirage F-1, el CASA C-101, CASA-Northrop F-5, los F-18 Hornet y los Eurofighter Typhoon.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.aviationcorner.net\/show_photo.asp?id=3954\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/avc_3954.jpg\" border=\"0\" alt=\"C.15-60\" title=\"C.15-60\" \/><\/a><br \/><small>McDonnell Douglas C-15 Hornet (EF-18A) C.15-60 \/ 12-18 fotograf\u00edado el 08\/05\/06 en Torrej\u00f3n (LETO) con el nuevo esquema de pintura que incluye la falza cabina. Fotograf\u00eda de Ruben Galindo Verdugo publicada en <a href=\"http:\/\/www.aviationcorner.net\/\" target=\"_blank\">Aviation Corner<\/a><\/small><\/p>\n<\/div>\n<p>Yo espero que estas decisiones se hayan tomado con criterios de eficacia en el combate y no porque sea menos costoso en horas de trabajo. A mi el color \u201cgris OTAN\u201d o \u201cgris superioridad a\u00e9rea\u201d no es que me disguste, pero me resulta algo mon\u00f3tono. Siempre es mejor que la ca\u00f3tica situaci\u00f3n de tiempos pasados en que el esquema de pintura de nuestros aviones deb\u00edan decidirlo los fabricantes y ten\u00edamos aviones en diferentes esquemas \u201clagarto\u201d como el del Mirage-III, o algo m\u00e1s \u201ccampero\u201d como el Mirage F-1 que luego se aplic\u00f3 mas o menos igual a algunos aviones de transporte, porque el H\u00e9rcules siempre conserv\u00f3 su personalidad en este aspecto.<\/p>\n<p>Pero siempre queda la a\u00f1oranza que como aficionado a las maquetas y al arte con motivo aeron\u00e1utico me producen los esquemas vistosos de pintura. Por suerte, junto a esta normalizaci\u00f3n en gris de las libreas en nuestra fuerza a\u00e9rea se han ido haciendo concesiones al <a href=\"http:\/\/en.wikipedia.org\/wiki\/Nose_art\">\u201cnose art\u201d<\/a> impensables en otros tiempos. As\u00ed vimos los nombres de pilotos y personal de mantenimiento en los aviones del destacamento \u201cIcaro\u201d, hemos visto pinturas especiales con motivo de aniversarios en el <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/338808860\/\">F-1 con motivo del IV Centenario del Quijote<\/a> o antes del <a href=\"http:\/\/www.jetphotos.net\/viewphoto.php?id=452173\">25 aniversario del Ala 14<\/a>, adem\u00e1s de los ya frecuentes <a href=\"http:\/\/www.aviationcorner.net\/show_photo.asp?id=10659\">esquemas de &#8216;Tigre&#8217;<\/a> de los aviones que toman parte en los <a href=\"http:\/\/www.aviationcorner.net\/show_photo.asp?id=11410\">\u00abTiger meet\u00bb<\/a>, sin olvidar al <a href=\"http:\/\/www.elperiodicoextremadura.com\/noticias\/noticia.asp?pkid=51763\">malogrado cap. Manuel Rivera Hern\u00e1ndez<\/a> que perdi\u00f3 la vida en el F-5 &#8216;Mago 01&#8217; que se hab\u00eda pintado con un esquema especial con motivo del 50 aniversario de la <a href=\"http:\/\/www.ala23.com\/\">Escuela de Caza y Ataque<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy estaba leyendo la Revista Espa\u00f1ola de Defensa. Se trata de la revista del ministerio, \u201cla defensa roja\u201d, as\u00ed conocida por el color de su portada, para diferenciarla de la \u201cdefensa negra\u201d del Grupo EDEFA. Uno de sus art\u00edculos, \u201cPintura &hellip; <a href=\"https:\/\/robertopla.net\/blog\/gris-cielo.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-aerotrastorno"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}