{"id":146,"date":"2007-02-20T02:15:19","date_gmt":"2007-02-20T00:15:19","guid":{"rendered":"http:\/\/robertopla.net\/blog\/buenafuente-o-solan-de-cabras.htm"},"modified":"2007-02-20T02:15:19","modified_gmt":"2007-02-20T00:15:19","slug":"buenafuente-o-solan-de-cabras","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/buenafuente-o-solan-de-cabras.htm","title":{"rendered":"Buenafuente o Solan de Cabras"},"content":{"rendered":"<p>El otro d\u00eda o\u00ed comentar a Mariona que la botella de agua de Sol\u00e1n de Cabras, la de pl\u00e1stico azul, no es reciclable, pero cuando he intentado comprobarlo en Google no he encontrado referencias claras. Por el contrario, en la p\u00e1gina de la empresa embotelladora he encontrado un manifiesto grandilocuente sobre <a href=\"http:\/\/www.solandecabras.es\/esp\/politica_medioambiental.html\" target=\"_blank\">su preocupaci\u00f3n por el medio ambiente<\/a> y en las <a href=\"http:\/\/www.ciao.es\/Opiniones\/Solan_de_Cabras_Agua_Mineral_Natural__616509\" target=\"_blank\">comparativas de Ciao<\/a> uno de los usuarios se moja y dice que <a href=\"http:\/\/www.ciao.es\/Solan_de_Cabras_Agua_Mineral_Natural__Opinion_1129250\" target=\"_blank\">\u00abeste pl\u00e1stico es PET y se puede reciclar\u00bb<\/a>.<\/p>\n<p>Esta noche, cuando la he visto le he preguntado por su fuente de informaci\u00f3n. Me ha dicho que escucha por las ma\u00f1anas el programa <a href=\"http:\/\/www.tvcatalunya.com\/ptvcatalunya\/tvcProgramaSeccio.jsp?idint=145947628&#038;seccio=tvcat&#038;pseccio=145947628\" target=\"_blank\">\u00abEls Matins\u00bb<\/a> de Josep Cun\u00ed en TV3. Presta mucha atenci\u00f3n al espacio de Josep Llu\u00eds Gallego sobre reciclaje. Como hemos podido comprobar en <a href=\"http:\/\/www.tvcatalunya.com\/3alacarta\/video.htm?ID=220613622&#038;CAT_ID=tvcat\" target=\"_blank\">el video del programa<\/a>, lo que dijo el otro d\u00eda es que los fabricantes se quejan porque resulta que la botella azul ha sido un \u00e9xito en la promoci\u00f3n de la marca ya que la diferencia notablemente de la competencia. Una diferenciacion muy deseable en el <a href=\"http:\/\/www.conmuchogusto.net\/email.asp?articleid=632\" target=\"_blank\">complejo mundo de las aguas embotelladas<\/a>, pero que como material de reciclaje es pejiguero ya que los tintes a\u00f1adidos al pl\u00e1stico no se pueden separar y obliga a crear una cadena de reciclado separada para estas botellas, lo que incrementa notablemente el coste de este proceso.<\/p>\n<p>Llegado a este punto no he tenido m\u00e1s remedio que llamar a Valencia a mi amigo Claudio seguro de que como industrial del sector, sabria darme una respuesta clara sobre el <a href=\"http:\/\/www.textoscientificos.com\/polimeros\/pet\" target=\"_blank\">PET<\/a> y la botella azul. Y as\u00ed ha sido. Claudio me ha explicado que el PET no puede ser sencillamente triturado y fundido para volverlo a reutilizar como los otros pl\u00e1sticos sino que debe pasar por un proceso de cristalizado y que este proceso consume mucha energ\u00eda, lo que encarece el proceso y lo hace menos rentable desde el punto de vista econ\u00f3mico y energ\u00e9tico. Por otra parte los tintes hacen que el material reciclado no pueda ser reutilizado para crear material transparente, y de hecho su comportamiento es poco predecible, con los consiguientes problemas para su utilizaci\u00f3n.<\/p>\n<p>Como conclusi\u00f3n, un agua cara, aunque bastante apreciada -no falta quien dice que <a href=\"http:\/\/www.bloj.net\/towsend\/cgi-bin\/archives\/2005\/07\/cumpleaaos.html\" target=\"_blank\">le sabe a rayos<\/a>, aunque \u00abcontra gustos&#8230;\u00bb- y cuya excelente imagen de marca lo es en detrimento de un medio ambiente que se vanaglorian de proteger, algo que tampoco es nuevo porque hoy en dia jurar amor eterno al medio ambiente es condicion indispensable para abrir un negocio, aunque en la mayoria de los casos pasa como en las relaciones del instituto: \u00abprometer hasta meter y una vez metido, olvidar lo prometido\u00bb.<\/p>\n<p>Hay quien sin embargo prefiere permanecer fiel a sus principios y el caso de Andreu Buenafuente es reconfortante. El pasado dia 8 <a href=\"http:\/\/www.elpais.com\/articulo\/radio\/television\/Buenafuente\/rechaza\/premio\/le\/concede\/Losantos\/elpepugen\/20070208elpepirtv_2\/Tes\" target=\"_blank\">El Pais publicaba la noticia<\/a> de que hab\u00eda rechazado el premio Micr\u00f3fono de Oro porque tambi\u00e9n se lo hab\u00edan concedido a Federico Jim\u00e9nez Losantos, director del programa La ma\u00f1ana de la Cope. Y es que dicen que todas las comparaciones son odiosas pero Andreu debe pensar que algunas mucho m\u00e1s. A mi <a href=\"http:\/\/www.andreubuenafuente.com\/\" target=\"_blank\">Buenafuente<\/a> adem\u00e1s de hacerme reir a mand\u00edbula batiente me cae genial porque cuando empez\u00f3 con su programa en TV3 rompi\u00f3 uno de los c\u00e1nones m\u00e1s imperturbables de la televisi\u00f3n p\u00fablica de Catalunya, usando el castellano en sus programas mezclado con el catal\u00e1n de una forma tan natural como ocurre aqui en la calle. Es solo un peque\u00f1o detalle que unido a su \u00e1cida y genial visi\u00f3n de la vida cotidiana le convierten a mi modo de ver en uno de los humoristas mas notables que en el mundo han sido.<\/p>\n<p>Seguro que hay quien est\u00e1 pensando que la asociaci\u00f3n de ideas para traer a Buenafuente a un escrito sobre aguas minerales tiene el prop\u00f3sito de hacer un jueguecito de palabras f\u00e1cil y no muy acertado, pero poca gente sabe &#8211; o si, \u00a1y yo que s\u00e9!&#8230;- que Andreu Buenafuente dibuja y no voy a decir si lo hace bien o mal, solo que a mi me gusta. As\u00ed que el otro d\u00eda repasando los dibujos de su web, me encontr\u00e9 uno \u00a1de una botella azul!<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.andreubuenafuente.com\/v1\/central.php?id=f109\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/buenafuente.jpg\" border=\"0\" alt=\"Botella Azul\" title=\"Botella Azul\" \/><\/a><\/p>\n<\/div>\n<p>No voy a hacer comentario alguno al respecto. Quien est\u00e9 libre de pecado, que tire la primera piedra. Yo soy el primero en reconocer que he sucumbido al encanto de la botella azul y aunque no la consumo con asiduidad -en casa filtramos el agua del grifo- he tenido una botella azul de pl\u00e1stico para enfriar en la nevera el agua filtrada y servirla en la mesa. Una botella que despu\u00e9s de estropearse por el calor al meter en ella un liquido caliente, fue a parar al contenedor de envases y ha sido sustituida por otra botella azul de litro de Solan de Cabras,&#8230;de cristal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El otro d\u00eda o\u00ed comentar a Mariona que la botella de agua de Sol\u00e1n de Cabras, la de pl\u00e1stico azul, no es reciclable, pero cuando he intentado comprobarlo en Google no he encontrado referencias claras. Por el contrario, en la &hellip; <a href=\"https:\/\/robertopla.net\/blog\/buenafuente-o-solan-de-cabras.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-146","post","type-post","status-publish","format-standard","hentry","category-inclasificable"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=146"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/146\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}