{"id":163,"date":"2007-03-18T15:48:42","date_gmt":"2007-03-18T13:48:42","guid":{"rendered":"http:\/\/robertopla.net\/blog\/software-libre-para-windows.htm"},"modified":"2007-03-18T15:48:42","modified_gmt":"2007-03-18T13:48:42","slug":"software-libre-para-windows","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/software-libre-para-windows.htm","title":{"rendered":"Software Libre para Windows"},"content":{"rendered":"<p>Hace ya a\u00f1os que tom\u00e9 la decisi\u00f3n de pasarme a <a href=\"http:\/\/es.wikipedia.org\/wiki\/Linux\" target=\"_blank\">Linux<\/a> y <a href=\"http:\/\/robertopla.net\/blog\/migracion-de-windows-a-linux.htm\" target=\"_blank\">ya expliqu\u00e9 en un articulo<\/a> el procedimiento que hab\u00eda usado, asi que no voy a repetirme.<\/p>\n<p>Sin embargo en la lista de correo de <a href=\"http:\/\/www.hispalinux.es\/\" target=\"_blank\">Hispalinux<\/a> han anunciado algo muy interesante: un CD de aplicaciones Windows. Aunque a los que conocen la pasi\u00f3n de los Linuxeros por su sistema operativo les pueda parecer poco creible y aalgunos linuxeros les parezca una blasfemia, lo cierto que es empezar a usar aplicaciones de <a href=\"http:\/\/www.gnu.org\/philosophy\/free-sw.es.html\">Software Libre<\/a> en Windows es la mejor transicion a Linux.<\/p>\n<p>Por ello recomiendo a todos los interesados que se pasen por <a href=\"http:\/\/sol4win.isadoraduncan.es\/\">la web de SOL4WIN<\/a>, de donde se pueden bajar este CD que se instala de una forma sencilla, sin hacer preguntas capciosas y nos permite empezar a usar las aplicaciones que luego podremos encontrar en Linux. Y todo de forma completamente legal y sin pagar un c\u00e9ntimo<\/p>\n<p>Es cierto que no est\u00e1 todo, pero confiamos que en pr\u00f3ximas versiones vayan ampliando el n\u00famero de aplicaciones. En la lista, por ejemplo se comentaba que para la mensajer\u00eda instantanea como el Messenger, lo mejor es usar <a href=\"http:\/\/www.jabberes.org\/\" target=\"_blank\">Jabber<\/a>, con el que se pueden enviar mensajes a usuarios de otras redes como MSN, AIM o Yahoo!. Yo particularmente he echado de menos <a href=\"http:\/\/www.proyectonave.es\/productos\/nvu\/\" target=\"_blank\">NVU<\/a>, <a href=\"http:\/\/www.inkscape.org\/?lang=es\" target=\"_blank\">Inkscape<\/a> y <a href=\"http:\/\/www.appservnetwork.com\/\" target=\"_blank\">AppServer<\/a>.<\/p>\n<p>Hay otras colecciones de software libre para windows, por ejemplo desde Colombia nos llega el <a href=\"http:\/\/www.aclibre.org\/openapps.html\" target=\"_blank\">proyecto ACLibre<\/a>, que publica el CD OpenApps es una recopilaci\u00f3n de software libre para ser empleado en windows y <a href=\"http:\/\/www.cdlibre.org\/\" target=\"_blank\">CD Libre<\/a> donde se encuentra todo tipo de software para Windows, libre o gratuito, que no es lo mismo, y sin ese punto de vista de transici\u00f3n a Linux aunque se se\u00f1ala que apliaciones tienen versi\u00f3n en Linux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace ya a\u00f1os que tom\u00e9 la decisi\u00f3n de pasarme a Linux y ya expliqu\u00e9 en un articulo el procedimiento que hab\u00eda usado, asi que no voy a repetirme. Sin embargo en la lista de correo de Hispalinux han anunciado algo &hellip; <a href=\"https:\/\/robertopla.net\/blog\/software-libre-para-windows.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-163","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}