{"id":206,"date":"2007-05-31T01:35:10","date_gmt":"2007-05-30T23:35:10","guid":{"rendered":"http:\/\/robertopla.net\/blog\/satisfaccion-del-cliente.htm"},"modified":"2007-05-31T01:35:10","modified_gmt":"2007-05-30T23:35:10","slug":"satisfaccion-del-cliente","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/satisfaccion-del-cliente.htm","title":{"rendered":"Satisfacci\u00f3n del Cliente"},"content":{"rendered":"<p>Es dif\u00edcil saber cuando un servicio o producto es bueno o es malo. Cada uno cuenta la guerra seg\u00fan le va. Hay veces que leo en las opiniones de productos cosas como \u00abEs la mejor c\u00e1mara del mundo, me ha llegado esta misma tarde y estoy muy contento con ella&#8230;\u00bb me quedo de piedra. \u00bfQue tipo de c\u00e1mara seria si despu\u00e9s de dos horas de funcionamiento y unas cuatro fotos su propietario estuviera disgustado con la compra?.<\/p>\n<p>Otras veces oigo a los amigos comentar que tal o cual proveedor de internet son muy r\u00e1pidos o que el mismo es mas lento que un caracol, su servicio de atenci\u00f3n al cliente es una tomadura de pelo y que pasan m\u00e1s tiempo sin servicio que conectados.<\/p>\n<p>Todas estas opiniones son subjetivas. Se refieren a hechos aislados y es no es fiable formarse un criterio bas\u00e1ndose en ellas. Una t\u00e9cnica que uso en cualquier encuesta de satisfacci\u00f3n de los clientes es eliminar los extremos y las opiniones precipitadas, emitidas en medio de la euforia de la compra o la ira del cliente descontento. Con el t\u00e9rmino medio analizo si existe una tendencia. Si la mayor\u00eda de los clientes medianamente satisfechos se\u00f1alan la corta duraci\u00f3n de las pilas como un defecto de una c\u00e1mara, hay muchas probabilidades de que ese sea un punto flaco del aparato. Las mismas aver\u00edas a diferentes clientes suelen indicar otros puntos d\u00e9biles y de la misma forma se detectan los puntos destacados.<\/p>\n<p>Los servicios t\u00e9cnicos son objetivos propicios y frecuente de nuestra animosidad. Cuando nuestro inseparable compa\u00f1ero no funciona adecuadamente, especialmente si el desv\u00edo de las especificaciones t\u00e9cnicas ha producido una p\u00e9rdida de datos y se prevee una separaci\u00f3n del mismo -que siempre es en el momento que m\u00e1s falta hace- quiz\u00e1s no es el mejor momento para emitir una opini\u00f3n objetiva sobre la eficacia y competencia del servicio t\u00e9cnico. Cualquier dispositivo es susceptible de una aver\u00eda  ning\u00fan servicio t\u00e9cnico tiene la soluci\u00f3n que el usuario querr\u00eda: que el incidente no se hubiera producido.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/acer1522.jpg\" alt=\"Acer Aspire 1522 WMLI\" title=\"Acer Aspire 1522 WMLI\"  style=\"border-style: none; float: left; position: relative; left: 0px; padding-right: 10px; padding-bottom: 10px; padding-top: 10px;\" \/>En mi caso, el cachivache d\u00edscolo era el port\u00e1til de mi hijo. Desde que lleg\u00f3 a casa no habia dado se\u00f1ales de vida en su interior la conexi\u00f3n Wi-fi que seg\u00fan especificaciones deb\u00eda poseer. Por pereza y porque no le era imprescindible, Roberto dej\u00f3 pasar el tiempo hasta que una serie de fallos se acumularon al tema del Wi-fi. Fallos en el teclado, la imposibilidad de restaurar el sistema y fallos en el bot\u00f3n de arranque llevaron finalmente el ordenador a las manos del servicio t\u00e9cnico de <a href=\"http:\/\/www.acer.es\/\">ACER<\/a>.<\/p>\n<p>Como pasaba el tiempo y no sab\u00edamos nada del ordenador, Mercedes llam\u00f3 y le dijeron que hab\u00edan enviado un presupuesto (que no hab\u00edamos recibido) y esperaban respuesta. Cuando Mercedes explic\u00f3 que se trataba de una reparaci\u00f3n en garant\u00eda y les volvi\u00f3 a enviar la fotocopia de la factura, ya solo tuvimos que esperar quince d\u00edas mas para tener el ordenador de vuelta en casa.<\/p>\n<p>As\u00ed contado ya parece poco agradable: m\u00e1s de dos meses sin ordenador y adem\u00e1s el caso del malentendido de la garant\u00eda. Sin embargo la cosa no hab\u00eda llegado a su fin. Al comprobar el estado del equipo, resulta que el dispositivo Wi-fi segu\u00eda sin dar se\u00f1ales de vida -\u00abNo Device\u00bb, m\u00e1s claro, el agua- y el bot\u00f3n de arranque segu\u00eda funcionando solo al segundo intento. Nueva llamada al servicio t\u00e9cnico y nuevo env\u00edo.<\/p>\n<p>Al hablar con el servicio t\u00e9cnico indiqu\u00e9, con muy poca f\u00e9, la circunstancia de que el ordenador ya habia estado alli dos meses y que teniendo previsto mi hijo viajar a Inglaterra seria muy de agradecer que tratasen de realizar la reparaci\u00f3n con car\u00e1cter urgente.<\/p>\n<p>De forma totalmente sorprendente, a los dos d\u00edas de recibir el equipo, ACER nos comunica que est\u00e1 reparado y viene de vuelta a casa. \u00a1Dos d\u00edas!. Quiz\u00e1s deber\u00eda esperar a escribir esta cr\u00f3nica a la recepci\u00f3n del equipo, pero el objeto que pretendo ilustrar con esta historia ya est\u00e1 completado. Un mismo servicio t\u00e9cnico puede acabar con nuestra paciencia o parecernos la organizaci\u00f3n m\u00e1s eficaz del mundo entero. Depende de como est\u00e9n de finos, supongo.<\/p>\n<p><strong>Actualizaci\u00f3n 02\/06\/2007 :<\/strong> Parece que con las prisas no estaban muy finos. El ordenador ha llegado pero se reinicializa cada poco tiempo sin causa aparente, el archivo &#8216;Launcher&#8217; tiene tendencia a volatilizarse, se producen paradas con &#8216;congelaci\u00f3n de la pantalla&#8217; y posterior cuelgue&#8230; Podria ser que despu\u00e9s de cambiar la placa base no hayan reinstalado el sistema operativo. Adem\u00e1s ahora lleva una versi\u00f3n de la BIOS anterior a la que traia de f\u00e1brica. A pesar de la duda se est\u00e1n mereciendo una puntuaci\u00f3n <strong>muy baja<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es dif\u00edcil saber cuando un servicio o producto es bueno o es malo. Cada uno cuenta la guerra seg\u00fan le va. Hay veces que leo en las opiniones de productos cosas como \u00abEs la mejor c\u00e1mara del mundo, me ha &hellip; <a href=\"https:\/\/robertopla.net\/blog\/satisfaccion-del-cliente.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-206","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}