{"id":25,"date":"2006-08-06T23:55:47","date_gmt":"2006-08-06T21:55:47","guid":{"rendered":"http:\/\/robertopla.net\/blog\/incendios-por-doquier.htm"},"modified":"2006-08-06T23:55:47","modified_gmt":"2006-08-06T21:55:47","slug":"incendios-por-doquier","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/incendios-por-doquier.htm","title":{"rendered":"Incendios por doquier"},"content":{"rendered":"<p>Esta tarde, cuando me he levantado de la siesta reglamentaria, el jard\u00edn estaba envuelto en una neblina gris\u00e1cea y hab\u00eda un fuerte olor a humo en toda la casa. En el estudio he encontrado a Mercedes con aspecto tranquilo, enfrascada con el ordenador, pasando cuentas de la econom\u00eda dom\u00e9stica o jugando a las cartas, vaya usted a saber.<br \/>\nDesde luego no ten\u00eda la actitud de alguien a quien se le estaba quemando la casa, as\u00ed que ya me he tranquilizado un poco, porque resulta imposible que el fino olfato de mi mujer no hubiera detectado el olor del humo y es igualmente improbable que estuviera sentada tranquilamente si la colcha que le hizo su madre estuviera en peligro de quemarse.<br \/>\n\u201cHay un incendio por aqu\u00ed cerca. Cuando he llevado a Beatriz al trabajo lo he visto\u201d, me ha dicho sin necesidad de que le preguntase. Me he acabado de poner la camiseta y me he ido a la puerta a verlo. Pensaba subir a un lugar elevado, pero no me ha hecho falta. Desde la puerta de casa se ve\u00eda  el origen de la inmensa humareda. He calculado que deb\u00eda encontrarse entre Pont de Molins y Cabanes.<br \/>\nHe ido a buscar el esc\u00e1ner de banda a\u00e9rea (un <a href=\"http:\/\/support.radioshack.com\/support_tutorials\/communications\/20-514.htm\" target=\"_blank\">RadioShack 20-514 PRO-89<\/a>) y sin demasiado esfuerzo he encontrado la frecuencia de coordinaci\u00f3n en 129,950. Alli me he quedado escuchando asombrado como a pesar de los esfuerzos de los helic\u00f3pteros el fuego avanzaba hacia Llers, una poblaci\u00f3n realmente muy cercana a Figueres.<br \/>\nHe salido y he subido a la terraza de la casa de enfrente con la c\u00e1mara de fotos por si alg\u00fan medio a\u00e9reo se aproximaba lo suficiente y desde alli pod\u00eda observar el ir y venir de los dos &#8216;Focas&#8217;, dos hidroaviones del <a href=\"http:\/\/perso.wanadoo.es\/43grupo\/\" target=\"_blank\">43 Grupo, los entra\u00f1ables &#8216;Botijos&#8217;<\/a> que iban y ven\u00edan desde la Bah\u00eda de Roses al incendio. Pasaban bastante lejos y esta imagen es todo lo que he conseguido.<\/p>\n<div style=\"text-align: center;\">\n<img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/botijo4322.jpg\" alt=\"Canadair CL-215T\" title=\"Canadair CL-215T\"  \/>\n<\/div>\n<p>Por suerte los esfuerzos han dado resultado y no he tenido ocasi\u00f3n de fotografiarlos m\u00e1s de cerca&#8230; a la altura de las obras del AVE la progresi\u00f3n del incendio hacia el oeste ha sido detenida y cuando los esfuerzos de  hidroaviones, helic\u00f3pteros y los Air Tractor -que ha llegado del sector de Banyoles como la caballer\u00eda en las pel\u00edculas- se ha concentrado sobre el flanco izquierdo, donde una granja estaba siendo rodeada por el incendio, las llamas han podido ser controladas y poco a poco han ido aumentando los intervalos entre llamadas.<br \/>\nA esas horas yo estaba ya echando un pestazo a humo como si hubiera pasado la tarde junto a una hoguera que arde mal. Cuando era peque\u00f1o y a la salida del colegio me entreten\u00eda en iniciar o compartir una hoguera en alguna casa abandonada, al llegar a casa, mi madre me dec\u00eda: \u201cHijo mio!, \u00bfde donde vienes?, \u00a1Pero si hueles a &#8216;pobre&#8217;!\u201d. Es verdad. Muchos de los pobres que encontr\u00e1bamos en aquellas casas abandonadas ol\u00edan al humo de las hogueras que constitu\u00edan su \u00fanico hogar. Esta tarde yo \u201col\u00eda a pobre\u201d, pero <a href=\"http:\/\/www.gencat.net\/interior\/esc\/docs\/esc_bombers.htm\" target=\"_blank\">los esforzados bomberos<\/a> que llevan varios d\u00edas de fuego en fuego descansando poco y trabajando mucho,  tendr\u00e1n seguramente m\u00e1s motivo de queja. Ahora, por la noche, cuando escribo esto, a\u00fan se oyen las sirenas de los vehiculos de los bomberos. Es poco probable que antes de ma\u00f1ana acaben los trabajos de extincion y figilancia de rescoldos.<br \/>\nAl volver a casa pensaba en el desastre que suponen estos incendios y como puede haber gente tan est\u00fapida o malvada que prenda fuegos intencionados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tarde, cuando me he levantado de la siesta reglamentaria, el jard\u00edn estaba envuelto en una neblina gris\u00e1cea y hab\u00eda un fuerte olor a humo en toda la casa. En el estudio he encontrado a Mercedes con aspecto tranquilo, enfrascada &hellip; <a href=\"https:\/\/robertopla.net\/blog\/incendios-por-doquier.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-aerotrastorno"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}