{"id":27,"date":"2006-08-11T23:47:57","date_gmt":"2006-08-11T21:47:57","guid":{"rendered":"http:\/\/robertopla.net\/blog\/un-fin-de-semana-largo.htm"},"modified":"2006-08-11T23:47:57","modified_gmt":"2006-08-11T21:47:57","slug":"un-fin-de-semana-largo","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/un-fin-de-semana-largo.htm","title":{"rendered":"Un fin de semana largo"},"content":{"rendered":"<p>No hay nada como un fin de semana largo para tomar una carretera y alejarse de las preocupaciones cotidianas. Eso precisamente es lo que pretend\u00edamos al ir a visitar a los Campanero en Castell\u00f3n.<\/p>\n<p>Miguel Angel y Mariona nos hab\u00edan hablado muchas veces de sus veranos en Benic\u00e1sim, en compa\u00f1\u00eda de los hermanos y sobrinos de Miguel Angel, de las barbacoas en familia y de las caballas a la plancha.<\/p>\n<p>Y este verano, como sus hijos han decidido hacer vida independiente, al menos desde el punto de vista geogr\u00e1fico, nos invitaron a visitarles un fin de semana y comprobar las bondades del sistema.<\/p>\n<p>Sin muchas dificultades encontramos el lugar, pr\u00f3ximo a la Avenida Ferrandis Salvador, una via urbana singular, porque a un lado y a otro del Cam\u00ed de la Ralla, que separa los t\u00e9rminos de Castell\u00f3n y Benicasim, tiene el mismo nombre y forma una \u00fanica v\u00eda, salvo por el peque\u00f1o detalle de que la numeraci\u00f3n es doble ya que cada ayuntamiento aplica la suya propia empezando desde el principio de &#8216;su&#8217; avenida situado en &#8216;su&#8217; municipio. Un bonito l\u00edo para el que no este advertido y busque una direcci\u00f3n.<\/p>\n<p>Nos intrig\u00f3 cual ser\u00eda el m\u00e9rito por el cual se le atribuia el nombre de tan extensa avenida. Aunque hubo quien apunt\u00f3 que &#8216;no era nadie&#8217; bas\u00e1ndose en que en el resto de las calles se mencionaba el oficio del patrono (Escritor, Doctor, Obispo&#8230;) tras un \u00e1rduo ejercicio de filtrado en Google he podido encontrar esta referencia que escribir\u00e9 aqui para los amantes de las hagiograf\u00edas: Don Jos\u00e9 Ferrandis Salvador fu\u00e9 Vicepresidente y Presidente de la Diputaci\u00f3n de Castell\u00f3n y como tal, diputado a Cortes desde 1946 a 1955.<\/p>\n<p>Por la noche nos acercamos al Grao de Castell\u00f3n y en un alarde de fortuna encontramos -sin espera- una mesa en la freiduria m\u00e1s afamada, aunque de la noche solo se salvaron con buena nota los boquerones en adobo que acompa\u00f1amos con unos chopitos de aprobado, unas patatas con ajo de mediano y unas almejas y mejillones de claro suspenso.<\/p>\n<p><!-- Start of Flickr Badge --><\/p>\n<div style=\"text-align:center;\">\n<style type=\"text\/css\">\n#flickr_badge_source_txt {padding:0; font: 11px Arial, Helvetica, Sans serif; color:#996600;}\n#flickr_badge_icon {display:block !important; margin:0 !important; border: 1px solid rgb(0, 0, 0) !important;}\n#flickr_icon_td {padding:0 5px 0 0 !important;}\n.flickr_badge_image {text-align:center !important;}\n.flickr_badge_image img {border: 1px solid black !important;}\n#flickr_www {display:block; text-align:center; padding:0 10px 0 10px !important; font: 11px Arial, Helvetica, Sans serif !important; color:#3993ff !important;}\n#flickr_badge_uber_wrapper a:hover,\n#flickr_badge_uber_wrapper a:link,\n#flickr_badge_uber_wrapper a:active,\n#flickr_badge_uber_wrapper a:visited {text-decoration:none !important; background:inherit !important;color:#330000;}\n#flickr_badge_wrapper {background-color:#FFFFFF;border: solid 1px #999966}\n#flickr_badge_source {padding:0 !important; font: 11px Arial, Helvetica, Sans serif !important; color:#996600 !important;}\n<\/style>\n<table id=\"flickr_badge_uber_wrapper\" cellpadding=\"0\" cellspacing=\"10\" border=\"0\">\n<script type=\"text\/javascript\" src=\"http:\/\/www.flickr.com\/badge_code_v2.gne?show_name=1&#038;count=4&#038;display=latest&#038;size=t&#038;layout=h&#038;source=user_set&#038;user=16652278%40N00&#038;set=72157594240005079&#038;context=in%2Fset-72157594240005079%2F\"><\/script><\/p>\n<td id=\"flickr_badge_source\" valign=\"center\" align=\"center\">\n<\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><!-- End of Flickr Badge --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay nada como un fin de semana largo para tomar una carretera y alejarse de las preocupaciones cotidianas. Eso precisamente es lo que pretend\u00edamos al ir a visitar a los Campanero en Castell\u00f3n. Miguel Angel y Mariona nos hab\u00edan &hellip; <a href=\"https:\/\/robertopla.net\/blog\/un-fin-de-semana-largo.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-27","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=27"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=27"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}