{"id":28,"date":"2006-08-12T10:04:29","date_gmt":"2006-08-12T08:04:29","guid":{"rendered":"http:\/\/robertopla.net\/blog\/un-punto-de-spotting.htm"},"modified":"2006-08-12T10:04:29","modified_gmt":"2006-08-12T08:04:29","slug":"un-punto-de-spotting","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/un-punto-de-spotting.htm","title":{"rendered":"Un punto de spotting"},"content":{"rendered":"<p>El apartamento donde veranean nuestros amigos tiene una situaci\u00f3n inmejorable. Pr\u00f3ximo a la playa, pero sobre todo justo al lado del Aer\u00f3dromo de Castell\u00f3n (LECN). Sin m\u00e1s esfuerzo que levantar la cabeza, se pueden divisar la mayor\u00eda de los tr\u00e1ficos, compuestos por avions ligeros y helic\u00f3pteros transportando pancartas publicitarias, aviones para la extinci\u00f3n de incendios, lanzamiento de paracaidistas, escuela de pilotos o aviones privados en tr\u00e1nsito. Una interesante variedad al alcance de un paseo por la avenida o una visita a las accesibles cabeceras de pista cuando se aburre uno de fotografiar panzas desde el cesped de la casa.<\/p>\n<p>Hice un buen n\u00famero de fotograf\u00edas y he subido algunas a <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/\" target=\"_blank\">mi espacio en Flickr<\/a>, aunque he de editar algunas para enviarlas a <a href=\"http:\/\/www.aviationcorner.net\/\" target=\"_blank\">Aviation Corner<\/a> o a <a href=\"http:\/\/www.jetphotos.net\/showphotos.php?userid=16320\" target=\"_blank\">Jetphotos<\/a>. Un trabajo entretenido y que me desanima muchas veces de intentar publicar en esas p\u00e1ginas que muchas veces tienen requerimientos por encima de mi tiempo y por que no decirlo, ya que est\u00e1 muy relacionado con el tiempo dedicado, de mis capacidades como fot\u00f3grafo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El apartamento donde veranean nuestros amigos tiene una situaci\u00f3n inmejorable. Pr\u00f3ximo a la playa, pero sobre todo justo al lado del Aer\u00f3dromo de Castell\u00f3n (LECN). Sin m\u00e1s esfuerzo que levantar la cabeza, se pueden divisar la mayor\u00eda de los tr\u00e1ficos, &hellip; <a href=\"https:\/\/robertopla.net\/blog\/un-punto-de-spotting.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","category-aerotrastorno"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}