{"id":289,"date":"2007-11-07T03:01:45","date_gmt":"2007-11-07T01:01:45","guid":{"rendered":"http:\/\/robertopla.net\/blog\/moviles-de-codigo-abierto.htm"},"modified":"2007-11-07T03:01:45","modified_gmt":"2007-11-07T01:01:45","slug":"moviles-de-codigo-abierto","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/moviles-de-codigo-abierto.htm","title":{"rendered":"M\u00f3viles de c\u00f3digo abierto"},"content":{"rendered":"<p>Hace d\u00edas se ven\u00eda especulando con la convocatoria de Google en la que se esperaba que anunciar\u00eda su entrada en el mercado de la telefon\u00eda movil con el lanzamiento de un terminal. Yo cre\u00eda que esto era un efecto de la aparici\u00f3n de <a href=\"http:\/\/www.apple.com\/es\/pr\/q207\/090107iphone.html\" target=\"_blank\">iPhone<\/a>, el tel\u00e9fono de Apple que ha conmocionado a los geeks de todo el mundo. Sin embargo es algo m\u00e1s, se trata de la madre de todas las batallas por el software que llevaremos en la mano.<\/p>\n<p>Lo que <a href=\"http:\/\/www.elpais.com\/articulo\/internet\/Google\/crea\/primera\/plataforma\/codigo\/abierto\/telefonia\/movil\/elpeputec\/20071105elpepunet_6\/Tes\" target=\"_blank\">Google ha anunciado<\/a> no es un tel\u00e9fono sino una soluci\u00f3n completa de tecnolog\u00edas de c\u00f3digo abierto para tel\u00e9fonos, basado en Linux, libre y abierto. El sistema se llama Android  y en breve los desarrolladores podr\u00e1n bajarse un <a href=\"http:\/\/es.wikipedia.org\/wiki\/SDK\" target=\"_blank\">SDK<\/a> gratuito.<\/p>\n<p>Si este software es libre, se habr\u00e1 dado un paso de gigante para que la informaci\u00f3n que nos rodea se codifique mediante est\u00e1ndares abiertos. Eso significar\u00eda que cualquiera podr\u00eda hacer o mejorar aplicaciones para aquellos objetos que usamos a diario. Que podr\u00edamos personalizar nuestra agenda o el cliente de correo electr\u00f3nico del m\u00f3vil-pda. Y para aquellos que no deseen ponerse a programar siempre habr\u00e1 alguien que lo haga y publique sus programas bajo licencia <a href=\"http:\/\/es.wikipedia.org\/wiki\/GPL\" target=\"_blank\">GPL<\/a>.<\/p>\n<p>Otro aspecto interesante es el elevado n\u00famero de compa\u00f1\u00edas de diferentes \u00e1mbitos que se han asociado con Google para apoyar esta plataforma. Desde fabricantes de ordenadores o m\u00f3viles a operadores telef\u00f3nicos, entre ellos la Telef\u00f3nica espa\u00f1ola.<\/p>\n<p>Si esto sale adelante el iPhone se va a quedar anticuado en muy poco tiempo y eso que <a href=\"http:\/\/www.archimadrid.es\/princi\/princip\/otros\/santoral\/santoral.htm\" target=\"_blank\">entre otros santos<\/a>, hoy siete de noviembre, es San Leopardo, que es el santo Patr\u00f3n del <a href=\"http:\/\/es.wikipedia.org\/wiki\/Mac_OS_X_v10.5\" target=\"_blank\">nuevo sistema Operativo de Apple<\/a>.<\/p>\n<p><strong>Actualizaci\u00f3n 15\/11\/07:<\/strong> <a href=\"http:\/\/www.error500.net\/licencia-apache-android\">Leo en Error500<\/a> que la licencia bajo la que se publicar\u00e1 Android no es <a href=\"http:\/\/es.wikipedia.org\/wiki\/GPL\" target=\"_blank\">GPL<\/a> sino la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Apache_License\">licencia Apache<\/a> que permite realizar obras derivadas sin necesidad de compartir el c\u00f3digo. Eso permitir\u00e1 a operadores telef\u00f3nicos realizar sus propias versiones o programas adaptados a sus terminales sin compartir c\u00f3digo con lo que no se dar\u00e1 el \u00abciclo virtuoso\u00bb de que todo aporte vuelva a la comunidad para enriquecer el proyecto. \u00bfEs mejor un poco que nada?. Veremos si con estas caracter\u00edsticas Android es capaz de desbancar a las soluciones propietarias o a los otros entornos de programacion para m\u00f3viles como <a href=\"http:\/\/www.symbian.com\/\">Symbian<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace d\u00edas se ven\u00eda especulando con la convocatoria de Google en la que se esperaba que anunciar\u00eda su entrada en el mercado de la telefon\u00eda movil con el lanzamiento de un terminal. Yo cre\u00eda que esto era un efecto de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/moviles-de-codigo-abierto.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-289","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/289\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}