{"id":298,"date":"2007-11-27T23:04:03","date_gmt":"2007-11-27T21:04:03","guid":{"rendered":"http:\/\/robertopla.net\/blog\/muy-liado.htm"},"modified":"2007-11-27T23:04:03","modified_gmt":"2007-11-27T21:04:03","slug":"muy-liado","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/muy-liado.htm","title":{"rendered":"Muy liado"},"content":{"rendered":"<p>Esta semana me ha pasado una situaci\u00f3n an\u00f3mala. A pesar de tener tres o cuatro ideas en mente para art\u00edculos del blog no he tenido oportunidad de escribirlos.<\/p>\n<p>Quiz\u00e1s si los hiciera m\u00e1s cortos o buscase menos datos antes de escribirlos habr\u00edan salido en un momento entre dos tareas como este, pero la verdad es que a pesar del elevado n\u00famero de art\u00edculos que han acabado figurando en la secci\u00f3n de &#8216;Fugaces&#8217;, no me gusta pasar de puntillas sobre los temas. Al fin y al cabo una de las satisfacciones que me da el blog es la de escribir y eso solo se produce escribiendo, para desesperaci\u00f3n de los que me leen.<\/p>\n<p>El motivo de mi absentismo estos d\u00edas ha sido que hemos cambiado de alojamiento la web de la <a href=\"http:\/\/www.aire.org\/\">Asociaci\u00f3n Aire<\/a>. El contrato nos expiraba el d\u00eda 29 de este mes y hab\u00edamos programado un traslado de datos con una seguridad y detalles similar a si traslad\u00e1semos \u00abLas Meninas\u00bb de Vel\u00e1zquez. Sin embargo, como suele ocurrir todo aquello que pod\u00eda salir mal, sali\u00f3 mal.<\/p>\n<p>Primero nuestro antiguo proveedor no entendi\u00f3 la fecha en que quer\u00edamos el &#8216;apag\u00f3n&#8217; y pr\u00e1cticamente nos desaloj\u00f3 sin preaviso. Por suerte hab\u00edamos hecho ya copia de seguridad de los datos, al menos de los m\u00e1s importantes. Pero tuve que ponerme el fin de semana a hacer el traslado como un loco.<\/p>\n<p>Las siguientes sorpresas fueron una serie de incompatibilidades de versiones entre la versi\u00f3n de php-Nuke que hab\u00edamos salvado y el del <a href=\"http:\/\/www.hostmonster.com\/\">nuevo servidor<\/a>. Instalamos el que nos ofrec\u00eda preinstalado el nuevo proveedor y vimos que era otra versi\u00f3n incompatible con el <a href=\"http:\/\/phpnuke.org\/\">php-Nuke<\/a> que ten\u00edamos antes y por tanto el formato de los datos que hab\u00edamos salvado.<\/p>\n<p>Llegados a este punto el esfuerzo que hab\u00eda que hacer para transformar los datos no compensaba ya que ten\u00edamos previsto migrar proximamente a <a href=\"http:\/\/www.joomlaspanish.org\/\">Joomla!<\/a> y tendriamos que repetir el proceso, asi que \u00bfpor qu\u00e9 no pasar directamente a Joomla!?.<\/p>\n<p>Instalado este <a href=\"http:\/\/es.wikipedia.org\/wiki\/CMS\">CMS<\/a>, resulta que est\u00e1 en ingl\u00e9s y el pack en espa\u00f1ol que encuentro es para la versi\u00f3n en pruebas (RC, Release Candidate ), asi que me toca descomprimir todo el paquete de la instalaci\u00f3n en espa\u00f1ol de la versi\u00f3n estable y subir al servidor los ficheros relacionados con el idioma. Y todo eso sin haber abierto el manual de la aplicaci\u00f3n.<\/p>\n<div style=\"text-align:center\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2070255868\/\" ><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2105\/2070255868_3b50282238.jpg\" width=\"455\" height=\"500\" alt=\"Portada de aire.org\" title=\"Portada de aire.org\" \/><\/a><\/p>\n<\/div>\n<p>Aprender como funciona una aplicaci\u00f3n al tiempo que la configuras puede ser entretenido. Eso es lo que he ido haciendo yo. La verdad es que <a href=\"http:\/\/www.joomlaspanish.org\/\">Joomla!<\/a> es sorprendente por la cantidad de cosas que permite configurar pero durante dos dias yo he andado dando palos de ciego. Ahora parece que cada cosa empieza a est\u00e1r en su sitio, pero he tenido la encuesta y otros m\u00f3dulos descuadrados todos estos dias.<\/p>\n<p>Espero que ma\u00f1ana podr\u00e9 por fin meterme con el <a href=\"http:\/\/es.wikipedia.org\/wiki\/SQL\">SQL<\/a> para hacer trasvases de datos y quiz\u00e1s me quede tiempo para escribir algo en el blog. A los amigos de Aire les he ido machacando con mis penas, con la remota esperanza de que alguno dijera, \u00ab<em>\u00a1vaya!, si creo que a mi me explicaron algo de esto&#8230;<\/em>\u00bb Y tambien, lo confieso, porque estaba necesitado de apoyo o en su defecto, solidaridad. &#8216;Que gente m\u00e1s maja!, todos se han mostrado muy solidarios. No hemos solucionado nada con eso, pero nos hemos quedado todos mas satisfechos. Nada como el calor de la amistad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana me ha pasado una situaci\u00f3n an\u00f3mala. A pesar de tener tres o cuatro ideas en mente para art\u00edculos del blog no he tenido oportunidad de escribirlos. Quiz\u00e1s si los hiciera m\u00e1s cortos o buscase menos datos antes de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/muy-liado.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-298","post","type-post","status-publish","format-standard","hentry","category-omblogo"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=298"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/298\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}