{"id":30,"date":"2006-08-12T23:45:47","date_gmt":"2006-08-12T21:45:47","guid":{"rendered":"http:\/\/robertopla.net\/blog\/lo-mas-importante.htm"},"modified":"2006-08-12T23:45:47","modified_gmt":"2006-08-12T21:45:47","slug":"lo-mas-importante","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/lo-mas-importante.htm","title":{"rendered":"Lo m\u00e1s importante"},"content":{"rendered":"<p>Sin duda alguna lo mas importante en nuestros viajes es el aspecto gastron\u00f3mico de los mismos. \u00bfQue es lo que comentamos cuando pasa el tiempo? no es la esbeltez de los arcos de aquella iglesia, ni los vivos colores del paisaje, ni siquiera las voluptuosas curvas de las ba\u00f1istas en la playa aunque todas esas cosas son sin duda bellas y admirables. Lo que de verdad comentamos en detalle, al llegar a casa o a\u00f1os despu\u00e9s son las comidas. los nuevos platos y recetas descubiertos, los sitios baratos y con preparados deliciosos.<\/p>\n<p>Este viaje tuvo dos momentos estelares. Uno de ellos ampliamente anunciado fu\u00e9 la barbacoa en casa de Alberto, el hermano de Miguel Angel. Las caballas a la plancha cubiertas con un picadillo de tomate, cebolla y pimiento no desmerecieron un \u00e1pice de su justa fama no por habitual ya en nuestras reuniones menos apreciada. Precedi\u00f3 a este manjar un pulpo a la gallega h\u00e1bilmente cocinado por Javier, oriundo de aquellas tierras y aerotrastornado. En estas reuniones con bastante gente -a la mayor\u00eda de la cual yo conoc\u00eda aquella noche- suele ocurrir que siempre parece que prestas poca atenci\u00f3n a un tema que te interesa, que queda enunciado pero no desarrollado competamente. Y eso me pas\u00f3 con Javier, con quien descubrimos que teniamos varias aficiones comunes relacionadas con la aeron\u00e1utica sin que pudieramos dedicarnos a charlar sobre ellas.<\/p>\n<p>Sin embargo la sorpresa de la noche fu\u00e9 la conexi\u00f3n alcarre\u00f1a, al resultar que estabamos cenando con unos parientes del sobrino de mi abuelo Julio Aragon\u00e9s con el que compart\u00eda nombre. Y es que este mundo es un pa\u00f1uelo. No me extender\u00e9 ahora en la relaci\u00f3n porque a\u00fan no tengo claro si yo mismo la he entendido y porque hoy mismo me est\u00e1n entrando otros datos sobre mi abuelo materno que le convierten en previsible objeto de un proximo art\u00edculo m\u00e1s extenso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin duda alguna lo mas importante en nuestros viajes es el aspecto gastron\u00f3mico de los mismos. \u00bfQue es lo que comentamos cuando pasa el tiempo? no es la esbeltez de los arcos de aquella iglesia, ni los vivos colores del &hellip; <a href=\"https:\/\/robertopla.net\/blog\/lo-mas-importante.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-30","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/30\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=30"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=30"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}