{"id":318,"date":"2007-12-30T19:10:42","date_gmt":"2007-12-30T17:10:42","guid":{"rendered":"http:\/\/robertopla.net\/blog\/el-principito.htm"},"modified":"2007-12-30T19:10:42","modified_gmt":"2007-12-30T17:10:42","slug":"el-principito","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/el-principito.htm","title":{"rendered":"El Principito"},"content":{"rendered":"<p>La primera vez que o\u00ed hablar del <a href=\"http:\/\/www.franciscorobles.com.ar\/libros\/principito\/pag00.htm\">Principito<\/a> estaba en el instituto en clase de Franc\u00e9s. Yo no atend\u00eda a las clases de franc\u00e9s porque no me era en absoluto necesario.<\/p>\n<p>Hab\u00eda empezado a ir a clases de Franc\u00e9s a los siete a\u00f1os a la Academia de \u00abMesi\u00e9 Borr\u00e1s\u00bb donde durante una hora al d\u00eda no se pod\u00eda hacer otra cosa que hablar franc\u00e9s. A pesar de que yo era realmente un resistente a la ense\u00f1anza el franc\u00e9s se convirti\u00f3 para mi en una lengua tan familiar que durante todo el bachiller solo ten\u00eda que ofrecerme voluntario para leer un d\u00eda en clase y tener ocasi\u00f3n de exhibir mi maravilloso acento para considerarme pr\u00e1cticamente aprobado. Las traducciones me resultaban simples y solo ten\u00eda que sortear las preguntas de gram\u00e1tica, la parte m\u00e1s debil de mi conocimiento de la lengua de Moliere.<\/p>\n<p>Por eso no atend\u00eda en clase. Era un esfuerzo in\u00fatil, puesto que ten\u00eda la asignatura aprobada casi de antemano. El libro era una novedad y prest\u00e9 un poco de atenci\u00f3n a mi ejemplar. Por supuesto estaba en franc\u00e9s lo que en principio no representaba ninguna dificultad para m\u00ed, pero aquel d\u00eda tuve que leer varias veces los primeros p\u00e1rrafos del libro para entender algo.<\/p>\n<p>\u00bfDibujos? Se trataba de una historia sobre una boa que se com\u00eda un elefante y cuyo dibujo parec\u00eda un sombrero. \u00a1Que estupidez! pens\u00e9. \u00bfComo se le ha ocurrido a esta mujer hacernos comprar un libro para ni\u00f1os?. Y all\u00ed acabo por entonces mi inter\u00e9s por el libro. \u00abHabla de la amistad y el amor, de los sue\u00f1os y de la vida\u00bb dec\u00eda la profesora, pero yo era un adolescente arrogante y est\u00fapido y no cre\u00ed una palabra.<\/p>\n<p>No s\u00e9 cuanto tiempo despu\u00e9s hice una lectura desganada de aquel libro que hab\u00eda calificado tan ligeramente. No recuerdo la raz\u00f3n que me impuls\u00f3 a retomar aquella lectura. Puede que el hecho de que su autor fuera un piloto o que incluyera dibujos me animase a investigar. Lo hice en un ejemplar en castellano, lo que a pesar de mis conocimientos de franc\u00e9s me era bast\u00e1nte m\u00e1s c\u00f3modo. Qued\u00e9 sorprendido. No era en absoluto un libro para ni\u00f1os y en \u00e9l encontr\u00e9 una serie de pensamientos profundos interesantes y muy \u00fatiles.<\/p>\n<p>Despu\u00e9s de aquella primera lectura han venido otras muchas. Sin duda alguna es el libro que he vuelto a leer m\u00e1s veces. <a href=\"http:\/\/www3.sympatico.ca\/gaston.ringuelet\/lepetitprince\/\">En espa\u00f1ol y en franc\u00e9s<\/a>. Solo en el texto en franc\u00e9s encuentro el aut\u00e9ntico sentido de algunas frases. Cuando el lenguaje expresa con maestr\u00eda los sentimientos se ci\u00f1e y apura los significados y sus traducciones son siempre aproximadas e incompletas.<\/p>\n<p>Esta tarde, puesto que solo dispon\u00eda de mi port\u00e1til, me he puesto a reorganizar ficheros en el disco duro y me he encontrado con una copia en formato PDF. Sin darme cuenta he le\u00eddo de nuevo sus cuarenta y cinco p\u00e1ginas. Y de nuevo he encontrado mensajes nuevos, ense\u00f1anzas que aun no hab\u00eda asimilado, retazos de belleza en frases olvidadas y sobre todo esa sensaci\u00f3n de que el libro habla de mi, o de unos sentimientos tan familiares como universales.<\/p>\n<p>No me acuerdo del nombre de mi profesora de franc\u00e9s, pero s\u00e9 que ten\u00eda raz\u00f3n: el libro habla del amor, de la amistad de los sue\u00f1os y de la vida.<\/p>\n<p>En muchas de las circunstancias que durante mi vida he encontrado la amistad, el amor o la muerte las palabras del Principito han supuesto un alivio, un consuelo, una ayuda o un est\u00edmulo. Es incre\u00edble como tan pocas p\u00e1ginas pueden encerrar tanta sabidur\u00eda. Por eso El Principito se ha convertido tambi\u00e9n en uno de los libros que m\u00e1s veces he citado en mis escritos.<\/p>\n<p>Despu\u00e9s de leerlo, no con los ojos que leen las letras sino con los que lee el coraz\u00f3n y la mente, ni el miedo ni la tristeza, la amistad o la alegr\u00eda , la vida o la muerte pueden volver a verse de igual forma. Pero es muy probable que haya quien lo lea y solo vea en \u00e9l un libro para ni\u00f1os. Ya se sabe: <em>las personas mayores no entienden nada<\/em>.<\/p>\n<div style=\"text-align:center;\">\n<p><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/principito.jpg\" alt=\"Principito\" title=\"Principito\" \/><\/p>\n<\/div>\n<blockquote>\n<ul>\n<li><em>Son como el zorro era antes, que en nada se diferenciaba de otros cien mil zorros. Pero yo le hice mi amigo y ahora es \u00fanico en el mundo.<\/em><\/li>\n<li><em>He aqu\u00ed mi secreto, que no puede ser m\u00e1s simple : s\u00f3lo con el coraz\u00f3n se puede ver bien; lo esencial es invisible para los ojos.<\/em><\/li>\n<li><em>Pero los ojos son ciegos. Hay que buscar con el coraz\u00f3n.<\/em><\/li>\n<li><em>Para los que viajan, las estrellas son gu\u00edas; para otros s\u00f3lo son peque\u00f1as lucec\u00edtas.<\/em><\/li>\n<\/ul>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La primera vez que o\u00ed hablar del Principito estaba en el instituto en clase de Franc\u00e9s. Yo no atend\u00eda a las clases de franc\u00e9s porque no me era en absoluto necesario. Hab\u00eda empezado a ir a clases de Franc\u00e9s a &hellip; <a href=\"https:\/\/robertopla.net\/blog\/el-principito.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-318","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}