{"id":319,"date":"2007-12-31T19:59:57","date_gmt":"2007-12-31T17:59:57","guid":{"rendered":"http:\/\/robertopla.net\/blog\/scribbler.htm"},"modified":"2007-12-31T19:59:57","modified_gmt":"2007-12-31T17:59:57","slug":"scribbler","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/scribbler.htm","title":{"rendered":"Scribbler"},"content":{"rendered":"<p>Ya no me acuerdo de que forma aterric\u00e9 en la p\u00e1gina de <a href=\"http:\/\/www.zefrank.com\/scribbler\/\">Scribbler<\/a>, pero pronto se convirti\u00f3 en un entretenimiento estupendo. Se trata de una herramienta de dibujo realizada en Flash que a partir de un dibujo que sirve de &#8216;simiente&#8217; genera una imagen formada por trazos mas o menos aleatorios.<br \/>\nSe puede controlar el color, el grosor y la transparencia de los trazos y desde luego el tiempo que se desea prolongar el proceso. Con estos factores podemos empezar a experimentar.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2151468633\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2386\/2151468633_ffb5386131_t.jpg\" width=\"100\" height=\"98\" alt=\"Modelo\"  title=\"Modelo\"\/><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2152260186\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2176\/2152260186_afdac04562_t.jpg\" width=\"100\" height=\"98\" alt=\"Robot\" title=\"Robot\" \/><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2152259544\/\" title=\"Pajarraco\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2292\/2152259544_ce6f46ce5e_t.jpg\" width=\"100\" height=\"98\" alt=\"Pajarraco\" title=\"Pajarraco\" \/><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2151465079\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2098\/2151465079_1b898c8a48_t.jpg\" width=\"100\" height=\"98\" alt=\"Robot espacial\" title=\"Robot espacial\" \/><\/a><\/p>\n<\/div>\n<p>Yo lo hice durante un tiempo, obteniendo una serie de im\u00e1genes interesantes, algunas de las cuales <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/sets\/72157603593905793\/\">he colgado en Flickr<\/a>. Las principales conclusiones a las que he llegado son accesibles a cualquiera que juegue un poco con Scribbler. La primera es que las lineas demasiado juntas, como les dedos de una mano, suelen acabar en zonas oscuras. Otra conclusi\u00f3n es que las mejores im\u00e1genes aparecen en unos segundos. Dejar demasiado tiempo ejecut\u00e1ndose el proceso no suele mejorar los resultados.<\/p>\n<p>Por otra parte, se echa en falta algunas opciones. La primera, la posibilidad de cargar las im\u00e1genes simiente desde un archivo. La segunda la de proteger \u00e1reas o centrar la actividad en \u00e1reas espec\u00edficas. Al aplicar segundas rondas de colores eso permitir\u00eda generar interesantes coloreados.<\/p>\n<p>Desde luego me gustar\u00eda tener el c\u00f3digo fuente del programa o una versi\u00f3n para ejecuci\u00f3n local con la que poder jugar m\u00e1s o modificar. Pero por el momento, no hay m\u00e1s.<\/p>\n<p>Scribbler es un juguete gr\u00e1fico interactivo del artista digital <strong>Ze Frank<\/strong> que tiene <a href=\"http:\/\/www.zefrank.com\/\">en su web<\/a> otros muchos entretenimientos y distracciones poco aconsejables si se tiene otra cosa importante que hacer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya no me acuerdo de que forma aterric\u00e9 en la p\u00e1gina de Scribbler, pero pronto se convirti\u00f3 en un entretenimiento estupendo. Se trata de una herramienta de dibujo realizada en Flash que a partir de un dibujo que sirve de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/scribbler.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-319","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}