{"id":334,"date":"2008-01-21T22:46:06","date_gmt":"2008-01-21T20:46:06","guid":{"rendered":"http:\/\/robertopla.net\/blog\/la-wii-de-los-vecinos.htm"},"modified":"2008-01-21T22:46:06","modified_gmt":"2008-01-21T20:46:06","slug":"la-wii-de-los-vecinos","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/la-wii-de-los-vecinos.htm","title":{"rendered":"La Wii de los vecinos"},"content":{"rendered":"<p>El fin de semana estuvimos jugando con la <a href=\"http:\/\/wii.nintendo-europe.com\/499.html\">Wii<\/a> en casa de los vecinos. Fu\u00e9 una experiencia curiosa, nunca hab\u00eda jugado con una consola m\u00e1s all\u00e1 de interesarme por la <a href=\"http:\/\/es.playstation.com\/ps2\/\">PS2<\/a> de mi hijo, con la que le vi jugar -hace unos a\u00f1os- un juego de coches que avanzaban por una gran ciudad li\u00e1ndose a tiros, y meti\u00e9ndose en peleas. Se la hab\u00eda comprado \u00e9l con su sueldo y ya era mayorcito para que me preocupase el efecto nocivo de la violencia del juego. A mi personalmente no me pareci\u00f3 interesante, como antes no hab\u00edan logrado atraerme los juegos en general ni las consolas en particular.<\/p>\n<p>He de reconocer que soy torpe con los juegos. Adem\u00e1s de las limitaciones f\u00edsicas o la falta de habilidad innata que pueda aportar personalmente, hay una cuesti\u00f3n obvia: Los juegos necesitan dos cosas que yo no tengo: un maquin\u00f3n y tiempo para practicar. Yo me meto enseguida en el circulo vicioso de \u00abme matan, me aburro, como me aburro no practico, como no practico no aprendo, si vuelvo a jugar, me matan y me aburro&#8230;\u00bb<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/wii_01.jpg\" style=\"border-style: none; float: left; position: relative; left: 0px; padding-right: 10px; padding-bottom: 10px; padding-top: 10px;\" alt=\"Mando wii\" title=\"Mando wii\" \/>Por la wii ten\u00eda la curiosidad de ver un sistema de juego diferente a los mandos con botones cuya \u00fanica finalidad es provocar una luxaci\u00f3n o calambres en los dedos. Hab\u00eda oido opiniones dispares sobre el realismo que aporta el uso del mando y tenia curiosidad por formarme mi propia opini\u00f3n.<\/p>\n<p>Como profano completo en el tema de consolas de videojuegos, la primera experiencia puede ser calificada de bastante positiva. La experiencia se ha reducido a los simuladores de deportes que acompa\u00f1an a la consola y aunque los resultados son variables, el conjunto es positivo. En aquellos que requieren la aplicaci\u00f3n directa de un movimiento con la mano, el <a href=\"http:\/\/wiiportal.nintendo-europe.com\/938.html\">uso del mando<\/a> es muy realista.<\/p>\n<p>Quiz\u00e1s lo menos interesante es el boxeo y el b\u00e9isbol. El primero exige un exceso de ejercicio poco compatible con un juego de sal\u00f3n y por ahora parece que aun no han encontrado la forma de que el jugador sienta los golpes que encaja de forma &#8216;realista&#8217;. En el B\u00e9isbol es posible que la escasa popularidad que tiene entre nosotros este deporte haga que no pongamos el inter\u00e9s suficiente en mejorar con el bate.<\/p>\n<p>Sin duda alguna tenis y sobre todo los bolos fueron la estrella de la jornada. Me sorprendi\u00f3 que en el juego las bolas tienden a salir tal y como nos salen cuando vamos a la bolera reproduciendo los defectos o efectos que le damos a la bola en la vida real, lo que es un indicio de su realismo.<\/p>\n<p>Tarde divertida y proyecto de repetir la sesi\u00f3n para las revanchas a falta de probar como se desarrolla el juego con varios mandos a la vez, por ejemplo en un doble de tenis. Bueno, sin duda, &#8230;\u00a1apartando los muebles!.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fin de semana estuvimos jugando con la Wii en casa de los vecinos. Fu\u00e9 una experiencia curiosa, nunca hab\u00eda jugado con una consola m\u00e1s all\u00e1 de interesarme por la PS2 de mi hijo, con la que le vi jugar &hellip; <a href=\"https:\/\/robertopla.net\/blog\/la-wii-de-los-vecinos.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-334","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}