{"id":341,"date":"2008-01-28T15:36:45","date_gmt":"2008-01-28T13:36:45","guid":{"rendered":"http:\/\/robertopla.net\/blog\/no-soy-un-antipatico.htm"},"modified":"2008-01-28T15:36:45","modified_gmt":"2008-01-28T13:36:45","slug":"no-soy-un-antipatico","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/no-soy-un-antipatico.htm","title":{"rendered":"No soy un antip\u00e1tico"},"content":{"rendered":"<p>El otro d\u00eda en el centro comercial nos encontramos con otra pareja. ella salud\u00f3 efusivamente a Mercedes, lo cual no me extra\u00f1\u00f3 pues mi mujer conoce a media provincia. Pero despu\u00e9s de darse dos besos con ella se dirigi\u00f3 a mi con una sonrisa de oreja a oreja y me plant\u00f3 dos besos, as\u00ed que como este es un paisaje frecuente yo sonre\u00ed tambi\u00e9n, la salud\u00e9 con efusi\u00f3n equivalente as\u00ed como a su acompa\u00f1ante, un hombre joven y de pelo corto que por su sonrisa tambi\u00e9n parec\u00eda conocerme. En cuanto nos separamos pregunt\u00e9 \u00bfquienes son estos?.<\/p>\n<p>Bueno, ella hab\u00eda trabajado con Mercedes, \u00e9l con mi hijo Roberto y hab\u00edamos coincidido en cenas de la empresa de mi mujer y en actos protocolarios por mi trabajo. El paisaje es frecuente. Todo el mundo parece conocerme, Mercedes desde luego conoce a todo el mundo pero yo nunca me acuerdo de nadie. Me resulta dif\u00edcil acordarme de caras y nombres pero a\u00fan m\u00e1s relacionarlos.<\/p>\n<p>No solo es un grave inconveniente profesional, pues me relaciono con mucha gente que espera que recuerde quienes son y como se llaman, tengo obligaciones puramente protocolarias que b\u00e1sicamente consisten en recordar caras, nombres y cargos y tengo a mi cargo muchas personas que suponen acertadamente que si no me acuerdo ni de su nombre dif\u00edcilmente lo har\u00e9 de sus problemas, con lo cual es imposible que pueda resolverlos o ayudarles a hacerlo.<\/p>\n<p>\u00bfComo me las apa\u00f1o?. Un pol\u00edtico me ense\u00f1\u00f3 un truco. Al saludar a alguien al que conoces, pero no recuerdas como se llama le dices, \u00abperdona,&#8230; \u00bfte llamas&#8230;?\u00bb. Si responde \u00abJos\u00e9\u00bb, t\u00fa respondes \u00abNo hombre!, eso ya lo s\u00e9, me refer\u00eda al apellido!\u00bb y naturalmente, si responde con el apellido, dices que lo recordabas y que le preguntabas por su nombre de pila. Yo no lo uso nunca y despu\u00e9s de confesarlo aqu\u00ed mejor que no lo haga (aunque seguro que no hay tanta gente que lee esto).<\/p>\n<p>Yo en lo profesional me apa\u00f1o con la inform\u00e1tica. En mi ordenador tengo fotos y nombres de todos los que trabajan conmigo y las repaso frecuentemente sin otro motivo que memorizarlas y siempre que tengo que despachar un asunto sobre alguien busco antes su foto. Modestia aparte, soy despistado, pero no un zoquete, as\u00ed que al poco tiempo ya recuerdo nombre y cara.<\/p>\n<p>En la vida social, me confieso. Si me preguntan, \u00bfte acuerdas de mi?, digo la verdad que suele ser, \u00abpues no, lo siento, soy muy despistado\u00bb. Procuro usar los trucos de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Dale_Carnegie\">Dale Carnegie<\/a>, de repetir el nombre de una persona cuando me la presentan pero exagerar este extremo te puede hacer parecer idiota, asi que entre despistado o idiota, me decanto por lo primero.<\/p>\n<p>Tambi\u00e9n apunto los nombres de las personas que me presentan y si se tercia el de sus esposas. Aunque soy del tipo de despistado que olvida consultar su agenda,  eso resulta de gran ayuda. Es una l\u00e1stima que las agendas que conozco para PDA no incluyan la fotograf\u00eda.<\/p>\n<p>Pero hay una situaci\u00f3n de la que normalmente soy poco consciente cuando ocurre, pero me temo que sucede m\u00e1s de una vez. Si voy solo por la calle, aunque suelo saludar a los que me saludan con equitativa efusi\u00f3n, seguro que hay muchos que se cruzan conmigo y piensan que no les saludo por soberbia, o simplemente porque soy un antip\u00e1tico.<\/p>\n<p>Me sabe muy mal porque soy bastante sociable, en general me gusta tratar y charlar con las personas y me encuentro c\u00f3modo con la gente honrada y agradable, sea cual sea su nivel social o sus otras circunstancias. Incluso tolero bastante bien a los que son secos, pesados o escasamente dotados. Quiz\u00e1s los que peor se me dan son los pedantes, pretenciosos, necios e incompetentes pero ellos lo notan enseguida porque uso con ellos sin piedad lo mas afilado de mi amplio repertorio de &#8216;patas de banco&#8217;.<\/p>\n<p>As\u00ed que en beneficio de todos aquellos que no saludo por la calle tengo que declarar solemnemente que opino que el saludo no se le niega a nadie y que si les parece que yo lo hago es, sencillamente porque no les reconozco. Lo siento: soy un despistado que lucha contra ello, pero desde luego <strong>no soy un antip\u00e1tico<\/strong>. Al menos intencionadamente, otra cosa son las gracias de cada uno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El otro d\u00eda en el centro comercial nos encontramos con otra pareja. ella salud\u00f3 efusivamente a Mercedes, lo cual no me extra\u00f1\u00f3 pues mi mujer conoce a media provincia. Pero despu\u00e9s de darse dos besos con ella se dirigi\u00f3 a &hellip; <a href=\"https:\/\/robertopla.net\/blog\/no-soy-un-antipatico.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-341","post","type-post","status-publish","format-standard","hentry","category-omblogo"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}