{"id":350,"date":"2008-02-08T10:54:49","date_gmt":"2008-02-08T08:54:49","guid":{"rendered":"http:\/\/robertopla.net\/blog\/genbeta-atacado.htm"},"modified":"2008-02-08T10:54:49","modified_gmt":"2008-02-08T08:54:49","slug":"genbeta-atacado","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/genbeta-atacado.htm","title":{"rendered":"Genbeta, atacado"},"content":{"rendered":"<p><a href=\"http:\/\/www.genbeta.com\/\">Genbeta<\/a> es un weblog colectivo dedicado al software y los servicios v\u00eda Internet, seg\u00fan reza su cabecera. Hoy est\u00e1 sufriendo un ataque de denegaci\u00f3n de servicio (DDOS) por no retirar una noticia en la que advert\u00eda a los usuarios de MSN, la red social de Microsoft sobre los peligros de quienes se dedican a establecer contactos con el \u00fanico inter\u00e9s de recopilar direcciones y generar SPAM.<\/p>\n<p>Esa es sin duda una lucha de &#8216;Los malos contra los buenos&#8217; y yo, desde luego, estoy a favor de &#8216;los buenos&#8217; y sobre todo de la libertad de expresi\u00f3n. Es intolerable que los chorizos intenten amedrentar, amenazar y atacar a quien no usa su libertad de expresi\u00f3n con arreglo a sus intereses mafiosos.<\/p>\n<p><a href=\"http:\/\/www.weblogssl.com\/\">WSL<\/a> la empresa propietaria de Genbeta <a href=\"http:\/\/www.weblogssl.com\/2008\/02\/07-ataque-de-ddos-a-genbeta\">ha publicado un comunicado<\/a> que ha sido reflejado en <a href=\"http:\/\/meneame.net\/\">Meneame<\/a> y que ha despertado la inmediata solidaridad de los internautas, solidaridad a la que quiero unirme enlaz\u00e1ndolos desde aqui y proponiendo que nos hagamos eco del post de Genbeta y lo reproduzcamos en todos los blogs que sea posible a fin de hacer inutil el ataque de los zombies.<\/p>\n<p>Yo ya he leido el art\u00edculo, que no me hab\u00eda interesado antes porque no uso MSN. Se titula <a href=\"http:\/\/www.genbeta.com\/2007\/11\/13-quieres-saber-quien-te-tiene-no-admitido-en-el-msn-pues-no-des-tu-contrasena-a-desconocidos\/\">\u00ab\u00bfQuieres saber qui\u00e9n te tiene no admitido\/eliminado en el MSN? Pues no des tu contrase\u00f1a a desconocidos\u00bb<\/a> y ha sido escrito por V\u00edctor Pimentel. \u00bfComo lo he conseguido?, es muy f\u00e1cil, solo teneis queusar Google y buscar <em>Genbeta<\/em> y luego entre comillas \u00ab<em>qui\u00e9n te tiene no admitido\/eliminado en el MSN<\/em>\u00bb sale el resultado en primer lugar, luego hay que escoger la opci\u00f3n \u00abCached\u00bb y vemos la copia del art\u00edculo guardada en la cach\u00e9 de Google.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Genbeta es un weblog colectivo dedicado al software y los servicios v\u00eda Internet, seg\u00fan reza su cabecera. Hoy est\u00e1 sufriendo un ataque de denegaci\u00f3n de servicio (DDOS) por no retirar una noticia en la que advert\u00eda a los usuarios de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/genbeta-atacado.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-350","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=350"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/350\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}