{"id":358,"date":"2008-02-17T10:07:10","date_gmt":"2008-02-17T08:07:10","guid":{"rendered":"http:\/\/robertopla.net\/blog\/spa.htm"},"modified":"2008-02-17T10:07:10","modified_gmt":"2008-02-17T08:07:10","slug":"spa","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/spa.htm","title":{"rendered":"Spa"},"content":{"rendered":"<p>Cuando estuvimos en B\u00e9lgica visitamos a Mercedes, la prima de Mercedes (son veintis\u00e9is Mercedes en la familia, asi que la coincidencia no es extra\u00f1a). La prima Mercedes nos llev\u00f3 de excursi\u00f3n. Desde <a href=\"http:\/\/maps.google.com\/maps?f=q&#038;hl=es&#038;geocode=&#038;ie=UTF8&#038;ll=50.547472,5.932617&#038;spn=0.42585,1.277161&#038;z=10\">Verviers<\/a>, hacia el sur, por un paisaje de bosques y peque\u00f1as monta\u00f1as que como era en febrero estaba nevado y nos pareci\u00f3 precioso.<\/p>\n<p>Llegamos a una ciudad peque\u00f1a llena de casas de ba\u00f1os termales cuyo nombre es Spa. R\u00e1pidamente asociamos este nombre a la designaci\u00f3n que hoy en dia se da a los Balnearios de toda la vida, las Casas de Ba\u00f1os, los servicios de ba\u00f1o y sauna comunes de un Hotel o hasta a la simple sauna dom\u00e9stica o el casi humilde ba\u00f1o de burbujas de jardin.<\/p>\n<p>El nombre, efectivamente, deriva de la ciudad de Spa, famosa por sus ba\u00f1os desde la \u00e9poca de los romanos pero que convirti\u00f3 esta actividad en una floreciente industria a partir del siglo XVI. Donde lo he encontrado mejor explicado es en la <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Spa_%28ville%29\">Wikipedia en franc\u00e9s<\/a>.<\/p>\n<p>Hoy en dia tenemos una fiebre de spa en el ramo de la hosteler\u00eda. Igual que en los a\u00f1os sesenta hasta los bares m\u00e1s r\u00fasticos se rotulaban de \u00absnack-Bar\u00bb, hoy no hay hotel que se precie que no sea un &#8216;Spa-Hotel&#8217;. Ya se sabe que en Espa\u00f1a lo extranjero siempre nos ha parecido m\u00e1s <em>&#8216;chic&#8217;<\/em>. Ya lo dec\u00eda Aparicio -un compa\u00f1ero de trabajo- cuando quer\u00eda se\u00f1alar que algo era lo \u00faltimo y lo m\u00e1s moderno dec\u00eda \u00ab<em>es lo que est\u00e1 entrando de Europa<\/em>\u00ab. Con ese aval, cualquier cosa parece merecer m\u00e1s atenci\u00f3n.<\/p>\n<p>El caso es que al margen de las modas y los nombres, un ba\u00f1o de agua caliente es una actividad relajante. Recuerdo las excursiones a los Ba\u00f1os de Mula, pr\u00f3ximos a Murcia. Nos los descubri\u00f3 nuestro amigo Pedro Javier y cuando iba a saltar en paraca\u00eddas a Alcantarilla era una forma estupenda de recuperar el cuerpo de los zurriagazos a los que se ve\u00eda sometido en los saltos.<\/p>\n<p>En Francia, cerca de las pistas de esqu\u00ed tenemos Saint Tom\u00e9 les Bains con sus piscinas al aire libre donde en pleno invierno puedes meterte en el agua caliente mientras la nieve cubre la orilla de la piscina. O los <a href=\"http:\/\/lesbainsde.llo.free.fr\/\">ba\u00f1os de Llo<\/a>, con unas instalaciones m\u00e1s modernas, saunas y ba\u00f1eras de masaje.<\/p>\n<p>Pero nunca hab\u00edamos podido disfrutar del alojamiento en un Hotel-Spa. O mejor dicho nunca hab\u00edamos podido usar los ba\u00f1os, porque en Mallorca si nos alojamos en un Hotel que ten\u00eda este servicio, pero intensamente dedicados a visitar la isla, no pasamos mucho tiempo en el Hotel.<\/p>\n<p>Este fin de semana hemos viajado a Lleida para celebrar el ochenta cumplea\u00f1os de mi padre que fue hace unos d\u00edas y el cincuenta y cinco aniversario de bodas de mis padres. Por Navidad mi hermano <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2269315651\/\">Luis Miguel y su mujer Mariantonieta<\/a> nos hab\u00edan regalado una estancia en el Hotel Nastasi, a disfrutar en fecha a determinar. As\u00ed que aprovechando la celebraci\u00f3n familiar lo hemos hecho efectivo este fin de semana.<\/p>\n<p>La experiencia ha estado muy bien. El Hotel est\u00e1 decorado con bastante buen gusto, esta limpio y bastante nuevo como corresponde a un hotel de lujo. Las instalaciones de ba\u00f1o -el spa- incluyen ba\u00f1eras de burbujas calientes y templadas, saunas y duchas de diversos tipos. Lo que m\u00e1s disfrutamos fue una ducha en la que te sientas sobre una especie de tumbona met\u00e1lica, que a pesar de lo que pueda esperarse no est\u00e1 fr\u00eda y te cae una ducha envolvente, desde arriba y los lados adem\u00e1s, por supuesto, de la ba\u00f1era caliente de burbujas donde solo se sale impulsado por la prudencia, porque el cuerpo lo que te pide es quedarse all\u00ed hasta disolverse como un azucarillo.<\/p>\n<p>En la habitaci\u00f3n del hotel hay un port\u00e1til a disposici\u00f3n de los hu\u00e9spedes, de forma que yo, que no me hab\u00eda tra\u00eddo el m\u00edo para desconectarme, no he podio resistir la tentaci\u00f3n de subir las fotos de la comida y escribir esta cr\u00f3nica.<\/p>\n<p>Si ten\u00e9is ocasi\u00f3n de hacer una escapada, os recomiendo una estancia en un Balneario o en un &#8216;Hotel-spa&#8217;. De verdad que el estr\u00e9s se disuelve en el agua caliente y se duerme como un bendito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando estuvimos en B\u00e9lgica visitamos a Mercedes, la prima de Mercedes (son veintis\u00e9is Mercedes en la familia, asi que la coincidencia no es extra\u00f1a). La prima Mercedes nos llev\u00f3 de excursi\u00f3n. Desde Verviers, hacia el sur, por un paisaje de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/spa.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-358","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=358"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/358\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}