{"id":378,"date":"2008-03-30T23:25:41","date_gmt":"2008-03-30T21:25:41","guid":{"rendered":"http:\/\/robertopla.net\/blog\/polaroidofilia.htm"},"modified":"2008-03-30T23:25:41","modified_gmt":"2008-03-30T21:25:41","slug":"polaroidofilia","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/polaroidofilia.htm","title":{"rendered":"Polaroidofilia, el Efecto Polaroid"},"content":{"rendered":"<p>Como invento, el sistema Polaroid de pel\u00edcula positiva instant\u00e1nea fue sin duda, ingenioso. Aunque Kodak hizo una pel\u00edcula similar, despu\u00e9s de un largu\u00edsimo pleito <a href=\"http:\/\/unifot.com.ve\/guiafotos\/es\/consumer\/pictureTaking\/filmDeveloping\/filmDevFAQs.html\">tuvo que retirarla del mercado<\/a> <sup><abbr title=\"En el enlace anterior, ver la \u00faltima pregunta\">(*)<\/abbr ><\/sup> por infringir las patentes de Polaroid.<\/p>\n<p>La pel\u00edcula Polaroid \u00abTime Zero\u00bb estaba formada por 15 capas, las exteriores de pl\u00e1stico transparente y antireflectante por un lado y la base de pl\u00e1stico negro por el otro. En medio, unas capas conten\u00edan los haluros de plata sensibles al azul, verde y cian junto a capas que conten\u00edan el revelador y colorante. Al producirse la exposici\u00f3n se impresionaban las capas sensibles y al extraer la pel\u00edcula de la c\u00e1mara se aprisionaba entre dos rodillos que &#8216;rompian&#8217; las barreras que liberaban los reveladores. El \u00absandwich\u00bb acababa en una capa reguladora de tiempo que finalmente dejaba pasar el \u00e1cido neutralizador del proceso y deten\u00eda el revelado.<\/p>\n<p>La imagen empezaba a aparecer alrededor de un minuto despu\u00e9s de salir de la c\u00e1mara y el revelado estaba completado en unos dos minutos. Por el contrario en la pel\u00edcula Kodak el revelado no finalizaba hasta pasados unos 10 min\u00fatos aunque an\u00e1lisis de la \u00e9poca deci\u00e1n que los colores de Kodak eran m\u00e1s reales con luz solar y flash.<\/p>\n<p>El proceso de revelado con l\u00edquidos o geles filtr\u00e1ndose entre capas pod\u00eda ser alterado ejerciendo presi\u00f3n sobre la fotograf\u00eda, deformando la imagen y alterando su color. Esto ha sido utilizado por algunos fot\u00f3grafos como un <a href=\"http:\/\/oriolalamany.blogspot.com\/2008\/02\/bye-bye-polaroid.html\">recurso art\u00edstico<\/a> con diversas variantes.<\/p>\n<p>El sistema Polaroid ha tenido entre los fot\u00f3grafos <a href=\"http:\/\/www.quesabesde.com\/noticias\/ran-el-cabrera,1_4019\">sus partidarios<\/a> con intenciones art\u00edsticas, algo que, por supuesto, <a href=\"http:\/\/www.quesabesde.com\/noticias\/polaroid-collections-ansel-adams-edwing-land,1_4149\">la propia compa\u00f1\u00eda ha fomentado<\/a>. Otros la usaron como recurso profesional de previsualizaci\u00f3n cuando ni se so\u00f1aba con la fotograf\u00eda digital, que ha sido quien ha dado la puntilla a las Polaroid.<\/p>\n<p>Entre los aficionados y los que han llenado con ellas sus \u00e1lbumes familiares, como simple entretenimiento o curiosidad, los usuarios ocasionales. Mi hija Beatriz tiene una c\u00e1mara Polaroid 635 CL, con la que ha hecho pocas fotos, sobre todo por que el precio de la pel\u00edcula quedaba muy lejos de su paga de estudiante.<\/p>\n<p>\u00bfQue har\u00e1n estos <a href=\"http:\/\/www.elmundo.es\/mundodinero\/2008\/02\/24\/economia\/1203853882.html\">entusiastas del sistema Polaroid<\/a>?. No se puede recrear una f\u00e1brica de pel\u00edcula en el garaje de casa. No hay formas artesanales -que yo conozca- de reproducir la pel\u00edcula. \u00bfQue ser\u00e1 de los miles de c\u00e1maras que conservar\u00e1n los coleccionistas?, Pasar\u00e1n a ser objetos muertos, a pesar de que su mec\u00e1nica o su electr\u00f3nica pueda seguir funcionando no podr\u00e1n realizar su funci\u00f3n vital, la que los define como c\u00e1maras instant\u00e1neas.<\/p>\n<p>Ya hay movimientos que solicitan de Polaroid o alg\u00fan otro fabricante <a href=\"http:\/\/www.savepolaroid.com\/\">que siga la producci\u00f3n<\/a> de este tipo de pel\u00edcula.<\/p>\n<p>Todo esto se debe al \u00ab<em>efecto Polaroid<\/em>\u00ab. Creo que es algo m\u00e1s que una pel\u00edcula peculiar o de la cuesti\u00f3n de la <a href=\"http:\/\/www.engadget.com\/2007\/11\/14\/polaroid-and-zink-develop-digital-instant-mobile-photo-printer\/\">copia instantanea<\/a>. Se trata de toda una est\u00e9tica que refleja parcialmente una \u00e9poca de nuestra historia. Hay quien encuentra un cierto encanto en la inmediatez o bien, como para los amantes de la <a href=\"http:\/\/www.lomospain.com\/lomografia\/lomografia.php\">Lomograf\u00eda<\/a>, rinden culto a la imperfecci\u00f3n, tambi\u00e9n est\u00e1n los que adoran ese margen blanco m\u00e1s ancho por debajo que da pi\u00e9 a escribir un comentario. Pero sobre todo, el eje central de la <strong>Polaroidofilia<\/strong> es el car\u00e1cter \u00fanico de cada imagen que no es una copia, sino un original.<\/p>\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2375798014\/\" ><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2345\/2375798014_960fb5d1bf_m.jpg\" style=\"border-style: none; float: left; position: relative; left: 0px; padding-right: 10px; padding-bottom: 10px; padding-top: 10px;\" width=\"200\" height=\"194\" alt=\"la familia en 1996\"  title=\"la familia en 1996\" \/><\/a>He buscado en nuestro \u00e1lbum familiar y he encontrado muy pocas instant\u00e1neas Polaroid. En nuestra antigua p\u00e1gina web familiar pusimos hace muchos a\u00f1os una foto navide\u00f1a hecha en casa de los vecinos con una Polaroid. Es tan horrorosa como cabria esperar, una especie de imagen de fotomat\u00f3n familiar. En Flickr tenemos una actualizaci\u00f3n de la misma y de la otra prueba que hicimos para la felicitaci\u00f3n de Navidad en nuestra p\u00e1gina familiar, escaneadas para este articulo.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2374963895\/\" ><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2186\/2374963895_f188a07fca_m.jpg\" width=\"199\" height=\"240\" alt=\"familia\" title=\"familia\" \/><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2374963139\/\" ><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2146\/2374963139_b20c8c7183_m.jpg\" width=\"197\" height=\"240\" alt=\"familia\" title=\"familia\" \/><\/a><\/p>\n<\/div>\n<p>Es muy probable que la gente no se resigne a perder esta est\u00e9tica y de la misma forma que aquellas viejas fotos en color sepia pasaron de necesidad a virtud, una b\u00fasqueda adecuada en la red nos proporciona m\u00faltiples formas de convertir una imagen digital en una imagen con &#8216;efecto polaroid&#8217;. Yo he hecho algunas pruebas que paso a explicar.<\/p>\n<p>Hay quien propone una reutilizaci\u00f3n de la carcasa de la c\u00e1mara para <a href=\"http:\/\/es.engadget.com\/2008\/02\/11\/no-tires-tu-vieja-polaroid-transformala-en-digital\/\">convertirla en una webcam<\/a>. Creo que es algo tan horrible como tener un b\u00faho disecado al lado del telefono.<\/p>\n<p>Manuel Barzi nos ofrece un <a href=\"http:\/\/manuelbarzi.com\/Polaroid\/\">programa en Java<\/a> para aplicar el efecto Polaroid. Solo hay que descargarlo y ejecutarlo (requiere <a href=\"http:\/\/www.java.com\/download\/\">Java Virtual Machine<\/a>). Tambien permite descargar la letra de tipo cursiva que utiliza por defecto. Solo hay que ejecutar el programa y arrastrar una imagen. Esta conserva las proporciones, por lo que en este caso yo la recort\u00e9 cuadrada antes de transformarla. Las proporciones de los bordes blancos no son las mismas que en una Polaroid aut\u00e9ntica cuyas dimensiones son de 89&#215;107 mm. con un recuadro para la imagen de 79&#215;79 mm. situado a 5 mm del borde superior y de los laterales y que deja un margen inferior de 23 mm. que invita a las anotaciones.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2374974481\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2372\/2374974481_657c83f212_m.jpg\" style=\"border: thin solid #c3c3c3;\" width=\"226\" height=\"240\" alt=\"Polaroid-Java\"  title=\"Polaroid-Java\"\/><\/a><\/p>\n<\/div>\n<p>Para cualquiera que sepa utilizar un programa como <a href=\"http:\/\/www.gimp.org.es\/\">GIMP<\/a>, a\u00f1adir estos m\u00e1rgenes a una imagen previamente recortada como cuadrada no es ningun misterio. Para calcular los m\u00e1rgenes laterales y superior hay que hacer la siguiente multiplicaci\u00f3n:<\/p>\n<div>\n<div style=\"text-align:center;\">\n<p><span style=\"border: thin solid #c3c3c3;padding:8px;\"><strong>Margen-lateral<\/strong> = 0,0633 x <strong>Lado<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<p> O esta otra para saber cual es la dimensi\u00f3n del margen inferior:<\/p>\n<div>\n<div style=\"text-align:center;\">\n<p><span style=\"border: thin solid #c3c3c3;padding:8px;\"><strong>Margen-inferior<\/strong> = 0,29 x <strong>Lado<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<p>Naturalmente <strong>Lado<\/strong> se refiere a la dimensi\u00f3n del lado de la fotograf\u00eda que hemos convertido en cuadrada. Si lo tomamos en pixeles y hemos hecho una imagen de 300&#215;300 pixeles, tendremos un margen lateral de 18,98734177 pixeles que podemos redondear tranquilamente a <strong>19<\/strong> y un margen inferior de 87,34177215 que dejaremos en 87. Estos m\u00e1rgenes pueden tener en las fotograf\u00edas reales hasta un mil\u00edmetro de error.<\/p>\n<p>Usando la herramienta \u00ab<em>Imagen\/Tama\u00f1o del lienzo<\/em>\u00bb podemos establecer los m\u00e1rgenes y centrar la imagen tal y como vemos en esta captura de pantalla.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2375004167\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3140\/2375004167_72bbb94e73.jpg\" style=\"border:none;\" width=\"450\" height=\"320\" alt=\"Efecto Polaroid - GIMP\" title=\"Efecto Polaroid - GIMP\" \/><\/a><\/p>\n<\/div>\n<p>Aunque hay sin duda muchos tutoriales en la red que explican cosas semejantes tanto <a href=\"http:\/\/www.gimp.org.es\/modules\/news\/article.php?storyid=78\">con GIMP<\/a> como <a href=\"http:\/\/www.parapente.net\/blogs\/nosoloparapente\/00049\">con Photoshop<\/a> o usando algun <a href=\"http:\/\/www.xyberneticos.com\/index.php\/2007\/06\/15\/efecto-polaroid-de-forma-facil-y-rapida-usando-javascript\/\">script en javascript<\/a>, estos son mis resultados con GIMP:<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2374974687\/\" title=\"rugby_gimp por Fotero, en Flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2094\/2374974687_7aff2742cb_m.jpg\" style=\"border: thin solid #c3c3c3;\" width=\"200\" height=\"240\" alt=\"rugby_gimp\" \/><\/a><\/p>\n<\/div>\n<p>Podemos usar <a href=\"http:\/\/lab.rails2u.com\/polaroize\/\">Polaroize<\/a>, una p\u00e1gina que demuestra el efecto de un script en Ruby y que usa las librer\u00edas ImageMagick. Lamentablemente la p\u00e1gina est\u00e1 en Japon\u00e9s y no permite descargar la imagen resultante. Yo lo he hecho mediante el procedimiento de copiar la pantalla en el portapapeles usando el bot\u00f3n <key>&#8216;Impr pant&#8217;<\/key>.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2374974585\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3267\/2374974585_cccbee0b59_m.jpg\" style=\"border-style: none; width=\"240\" height=\"233\" alt=\"Polaroize\" title=\"Polaroize\" \/><\/a><\/p>\n<\/div>\n<p>Mucho m\u00e1s \u00fatil resulta <a href=\"http:\/\/polaroidonizer.b3ta.org\/\">Polaroid-o-nizer<\/a> que aunque tampoco permite descargar las im\u00e1genes (pero si subirlas a <a href=\"http:\/\/imageshack.us\/\">ImageShack<\/a>) una de sus ventajas es que permite indicar la inclinaci\u00f3n con que se quiere el resultado,<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2375879160\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3280\/2375879160_e3a3ac4c56_m.jpg\" style=\"border:none;\" width=\"191\" height=\"240\" alt=\"Polaroid-o-nize\" \/><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2375043569\/\" title=\"rugby_onize2 por Fotero, en Flickr\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2137\/2375043569_e31fff15ef_m.jpg\" style=\"border:none;\" width=\"206\" height=\"240\" alt=\"Polaroid-o-nize\"  title=\"Polaroid-o-nize\" \/><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como invento, el sistema Polaroid de pel\u00edcula positiva instant\u00e1nea fue sin duda, ingenioso. Aunque Kodak hizo una pel\u00edcula similar, despu\u00e9s de un largu\u00edsimo pleito tuvo que retirarla del mercado (*) por infringir las patentes de Polaroid. La pel\u00edcula Polaroid \u00abTime &hellip; <a href=\"https:\/\/robertopla.net\/blog\/polaroidofilia.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-378","post","type-post","status-publish","format-standard","hentry","category-fotografia-2"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/378\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}