{"id":427,"date":"2008-06-21T23:59:22","date_gmt":"2008-06-21T21:59:22","guid":{"rendered":"http:\/\/robertopla.net\/blog\/viena21.htm"},"modified":"2008-06-21T23:59:22","modified_gmt":"2008-06-21T21:59:22","slug":"viena21","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/viena21.htm","title":{"rendered":"Aqui tambi\u00e9n bailan los caballos"},"content":{"rendered":"<p>El bufet del Tower Airo no era nada del otro mundo. Ten\u00eda adem\u00e1s de forma inexplicable tres niveles: los grupos en un comedor, los hu\u00e9spedes \u201cnormales\u201d en otro y una tercera categor\u00eda en la cafeter\u00eda que por el surtido del bufet deb\u00eda ser de hu\u00e9spedes \u201cselectos\u201d  venir rebotados de otro hotel nos incluy\u00f3 solo en la categor\u00eda de \u201cnormales\u201d. Nada m\u00e1s desayunar Miguel Angel se fue en taxi al \u201cTiket point\u201d a ver si encontraba entradas para el partido. Por si acaso me hab\u00eda vuelto loco me pregunt\u00f3 si querr\u00eda ir en caso de que hubiera entradas. No se lo tuve en cuenta y sencillamente le dije que \u201cpor supuesto que no\u201d. Uno no abdica de sus principios porque est\u00e9 en Viena o haya entradas.<\/p>\n<p>Despu\u00e9s de recoger el poco equipaje que hab\u00edamos desplegado nos llevaron en taxi al otro hotel, donde dejamos las maletas para irnos a ver el espect\u00e1culo de los caballos de la <a href=\"http:\/\/www.srs.at\/\">Escuela de Equitaci\u00f3n Espa\u00f1ola de Viena<\/a>. No ten\u00edamos entradas porque el proceso de adquirirlas por Internet era sorprendente. Pod\u00edan adquirirse en l\u00ednea pero la \u00fanica forma de entrega contemplada era el env\u00edo por correo certificado. Es como si despu\u00e9s de recibir un fax para entregarlo lo tradujeran a morse. Por supuesto un intenso intercambio de mensajes de correo electr\u00f3nico no permiti\u00f3 encontrar una alternativa viable. Muy germ\u00e1nicos ellos, los austriacos carecen tambi\u00e9n de imaginaci\u00f3n para salirse de la raya pintada en el suelo por m\u00e1s l\u00f3gica que ello tenga.<\/p>\n<p>Tuvimos suerte y a pesar de las amabil\u00edsimas y err\u00f3neas indicaciones de una se\u00f1ora que viajaba en el tranv\u00eda, llegamos sin contratiempos a la plaza Josef I donde nos encontramos con Miguel Angel, euf\u00f3rico porque hab\u00eda encontrado entradas para el partido de f\u00fatbol Espa\u00f1a-Italia y entramos a ver el espect\u00e1culo ecuestre comprando en taquilla unas entradas del piso superior desde donde lo vimos bastante bien <a href=\"http:\/\/www.wien.info\/article.asp?IDArticle=12432\">el espect\u00e1culo<\/a> que resulta impresionante.<\/p>\n<p>Aunque los movimientos de los caballos que parecen bailar y que son coordinados en todo momento fascinan a cualquiera aunque no entienda de caballos, las explicaciones de un experto son muy \u00fatiles para apreciar ejercicios de gran dificultad como el galope lento o los cambios de pata cada pocos pasos. Mariona nos explicaba los detalles t\u00e9cnicos que apreciamos mucho m\u00e1s que los parlamentos del presentador entre un ejercicio y otro, en un correct\u00edsimo alem\u00e1n y un ininteligible ingl\u00e9s.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/flickr.com\/photos\/fotero\/2611995376\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3145\/2611995376_efcb81bb44_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611995802\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3023\/2611995802_a93de0f1f5_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611162801\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3204\/2611162801_0069a68844_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611163321\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3147\/2611163321_ff84abf768_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2611998300\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3193\/2611998300_b217c71581_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611164845\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3163\/2611164845_2c61fe3d77_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611999606\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3046\/2611999606_2657dda586_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612000366\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3035\/2612000366_fe2d7d108b_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2612000594\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3186\/2612000594_68782a04fc_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612000972\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3118\/2612000972_a7e1097d92_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611167199\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2205\/2611167199_d30916e315_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611167555\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3177\/2611167555_7fa440666b_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2612002212\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3212\/2612002212_92660e1ebd_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611168839\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2065\/2611168839_7840391af7_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612003542\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3110\/2612003542_7667ae4a75_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612004498\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3037\/2612004498_900b96b332_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<\/p>\n<\/div>\n<p>Aunque estaba rigurosamente prohibido \u201cpara no asustar a los caballos\u201d, yo hice fotos tranquilamente pues no usaba flash y con el ruido que hab\u00eda estoy seguro que los caballos no oir\u00edan bajar el bot\u00f3n de mi c\u00e1mara digital.<\/p>\n<p>A la salida mientras pens\u00e1bamos a donde dirigirnos ca\u00edmos en la cuenta de que era s\u00e1bado y por tanto el \u00fanico d\u00eda que en el <a href=\"http:\/\/www.hotelcapri.at\/es-viena-mercado_de_golosinas_naschmarkt.shtml\">Flohmarkt<\/a> o mercado de las pulgas se pod\u00edan ver los puestos de antig\u00fcedades. All\u00e1 que fuimos y nos dimos un paseo por un mercado de frutas y verduras sorprendente, lleno de olores y abarrotado de frutas ex\u00f3ticas de las m\u00e1s diversas procedencias que hac\u00eda suspirar a Mercedes, \u00a1quien tuviera este mercado en Figueres!, dec\u00eda.<\/p>\n<p>Paramos a tomar una cerveza en un puesto que ten\u00eda buena pinta. Al leer la gu\u00eda nos dimos cuenta de que estaba recomendado. Decidimos comer en otro que recomendaba y que por la numeraci\u00f3n no deb\u00eda andar lejos. Nos levantamos y dimos dos o tres vueltas busc\u00e1ndolo y comprobando que la numeraci\u00f3n segu\u00eda un criterio ca\u00f3tico para finalmente encontrarlo. Era justamente el puesto que estaba delante de donde nos hab\u00edamos tomado la cerveza. Lo ten\u00edamos a dos metros. El lugar se llama \u201cdeli\u201d y los men\u00fas, baguels incluidos nos recordaron las comidas de Nueva York, comimos estupendamente y salimos a dar una vuelta por el resto del mercado, que finaliza a las 17:00 aunque a las 16:30 hab\u00eda puestos que ya estaban recogiendo.<\/p>\n<p>Mariona encontr\u00f3 una botella de cristal blanco para su colecci\u00f3n, Mercedes no encontr\u00f3 los pendientes ni piezas iguales para montarlos de coral rosa que deseaba para hacer juego con un collar de ese color y material y en general el lugar nos pareci\u00f3 muy interesante aunque la solana de la tarde animaba poco a entretenerse.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/flickr.com\/photos\/fotero\/2611177115\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3019\/2611177115_54c46e3952_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612011876\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2251\/2612011876_815238145f_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612012374\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3039\/2612012374_97be1894da_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611178439\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3089\/2611178439_328663c3ff_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2612013562\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3108\/2612013562_88a63149f6_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612014076\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3056\/2612014076_bbcab9a766_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2611180345\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3155\/2611180345_f8dfcc4040_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2612015218\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3009\/2612015218_95688c583a_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2611181329\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3091\/2611181329_d044b1035c_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2614810520\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3081\/2614810520_5c0b3e54db_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2613981091\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3070\/2613981091_ea6385b5c6_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2613981645\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3231\/2613981645_62b6bb87af_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<br \/><a href=\"http:\/\/flickr.com\/photos\/fotero\/2613981949\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3046\/2613981949_aeb7bc0494_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2613982329\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3045\/2613982329_7d57fbb19c_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2613982707\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3102\/2613982707_f234550d4e_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2614813172\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3222\/2614813172_6941f0b2f3_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<\/p>\n<\/div>\n<p>Regateando como un jabato Miguel Angel consigui\u00f3 hacerse con un equipo completo de \u201chincha\u201d para acudir al partido: Chistera y bufanda de los colores nacionales y bandera espa\u00f1ola. Y de esa guisa se pase\u00f3 hasta el hotel jaleado y admirado por cuantos se cruzaban en nuestro camino incapaz de pasar desapercibido.<\/p>\n<p>Despu\u00e9s de una siesta reparadora hemos dado un paseo por el centro, visitando la catedral para acabar cenando en <a href=\"http:\/\/www.figlmueller.at\/\">Figlm\u00fcller<\/a> un restaurante que recomendaba la gu\u00eda, de larga tradici\u00f3n y excelente cocina tradicional. Para empezar no ten\u00edan cerveza, solo el vino de fabricaci\u00f3n propia -excelente blanco, por cierto- y las raciones eran m\u00e1s que generosas.  El filete empanado (<em>Figlm\u00fcller Schnitzel<\/em>) se salia sobradamente por todos los bordes del plato y la ensalada de patatas que lo acompa\u00f1a (<em>Erd\u00e4pfel-Vogerlsalat<\/em>), en plato aparte es realmente deliciosa. Tambi\u00e9n probamos el Emenntal empanado (<em>Emmentaler gebacken mit Sauce Tartare<\/em>) y el <em>Goulash<\/em> con gnoquis. Pero hay que ir con hambre acumulada para salir indemne de las cantidades de cada plato. Yo solo consegu\u00ed dormir tranquilo aquella noche gracias a mi previsi\u00f3n al llevar varias dosis de \u201c<em>Almax<\/em>\u201d. Sin embargo la cuenta fue bastante moderada.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/flickr.com\/photos\/fotero\/2626234104\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3108\/2626234104_7836483912_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2626234714\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3165\/2626234714_39d666304e_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2626235726\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3143\/2626235726_2405a7fdb1_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<a href=\"http:\/\/flickr.com\/photos\/fotero\/2625414627\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3004\/2625414627_f946b2bb6e_s.jpg\" style=\"border:none;\"><\/a>&nbsp;<\/p>\n<\/div>\n<p>Antes de ir al hotel decidimos dar una vuelta y aprovechando la <a href=\"http:\/\/www.wien.info\/article.asp?IDArticle=6050\">Viena Card<\/a>, nuestro vale de transporte dimos una vuelta nocturna en el tranvia numero uno, para ver los edificios iluminados sin hacer sufrir los pies. Sin embargo, el calor sofocante no nos dej\u00f3 disfrutar completamente del paseo y llegamos al hotel cansados y acalorados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andanzas gastronomicas y tur\u00edsticas en Viena <a href=\"https:\/\/robertopla.net\/blog\/viena21.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[24,39,128,357,424,360],"class_list":["post-427","post","type-post","status-publish","format-standard","hentry","category-viajes","tag-amigos","tag-austria","tag-familia","tag-viaje","tag-viajes","tag-viena"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}