{"id":462,"date":"2008-09-17T21:29:00","date_gmt":"2008-09-17T19:29:00","guid":{"rendered":"http:\/\/robertopla.net\/blog\/carotas.htm"},"modified":"2008-09-17T21:29:00","modified_gmt":"2008-09-17T19:29:00","slug":"carotas","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/carotas.htm","title":{"rendered":"Carotas"},"content":{"rendered":"<p>Hay quien considera que hacer muecas delante de un espejo es una actividad poco seria. Efectivamente lo es y precisamente por eso, resulta altamente recomendable.<br \/>\nLa risa es un recurso terap\u00e9utico muy indicado para numerosas dolencias f\u00edsicas y ps\u00edquicas y el humor es la farmacia siempre dispuesta para proporcionarnos ese remedio. Tener la capacidad de reirse de uno mismo y con uno mismo, osea eso socialmente tan denostado de &#8216;<em>re\u00edrse los propios chistes<\/em>&#8216; es como llevar encima un botiqu\u00edn de urgencias.<br \/>\nTampoco es cuesti\u00f3n de exhibirse frecuentemente en medio de un arrebato de autodiversi\u00f3n. No es que la gente sean unos muermos, pero aunque podamos abstraernos moment\u00e1neamente de la realidad, no es prudente evitarla constantemente y en el mundo real la cordura y la locura, el respeto, el cr\u00e9dito y la opini\u00f3n se ven fuertemente influidos por la apariencia externa y los modales. Una cosa es ser independiente y otra, asocial.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2863353439\/\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3236\/2863353439_80837e78c4.jpg\" style=\"border:none;width:450px;height:338px;\" alt=\"Carotas\" title=\"Carotas\" \/><\/a><\/p>\n<\/div>\n<p>El otro d\u00eda estuve explorando las utilidades que acompa\u00f1an a la <a href=\"http:\/\/www.logitech.com\/index.cfm\/webcam_communications\/webcams\/devices\/4266&#038;cl=es,es\">QuickCam<\/a>, una webcam de Logitech que compr\u00e9 en la <a href=\"http:\/\/www.campus-party.es\/\">Campus Party<\/a>. Y estuve haciendo pruebas con unos efectos de v\u00eddeo que deforman la imagen. Pensando en como aplicarlo a la caricatura, me puse a hacer muecas y &#8216;poner caras&#8217; autofografi\u00e1ndome en cada una de ellas. Esta imagen es parte del resultado visible y puede que de aqui salga alg\u00fan que otro dibujo, pero la mejor parte me la llev\u00e9 divirti\u00e9ndome como delante de un espejo. \u00bfTen\u00e9is una webcam? Haced un poco el payaso, divertiros y re\u00edr con vuestro mejor amigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay quien considera que hacer muecas delante de un espejo es una actividad poco seria. Efectivamente lo es y precisamente por eso, resulta altamente recomendable. La risa es un recurso terap\u00e9utico muy indicado para numerosas dolencias f\u00edsicas y ps\u00edquicas y &hellip; <a href=\"https:\/\/robertopla.net\/blog\/carotas.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-fugaces"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}