{"id":464,"date":"2008-09-25T12:34:08","date_gmt":"2008-09-25T10:34:08","guid":{"rendered":"http:\/\/robertopla.net\/blog\/museo-de-la-retirada.htm"},"modified":"2008-09-25T12:34:08","modified_gmt":"2008-09-25T10:34:08","slug":"museo-de-la-retirada","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/museo-de-la-retirada.htm","title":{"rendered":"Museo de la retirada"},"content":{"rendered":"<p>La semana pasada pude ir a ver el Museo de la Retirada, en Camprod\u00f3n. Cuando se inaugur\u00f3 este verano no pude ir porque estaba fuera de Figueres y le hab\u00eda prometido a Alejandro Cuadrado, su propietario que buscar\u00eda un d\u00eda para acercarme a verlo.<br \/>\nEl museo es una modesta pero interesante exposici\u00f3n de la colecci\u00f3n particular de Alejandro. Aficionado a la historia es una de esas personas que ha hecho posible que muchas cosas que en su d\u00eda solo eran trastos viejos se conviertan en antiguas y hoy puedan darnos testimonio de un pasado que es patrimonio de todos.<br \/>\nPor una parte est\u00e1n las armas abandonadas por el Ej\u00e9rcito republicano en su retirada. Todas est\u00e1n expuestas con el \u00f3xido y hasta casi con el barro que se acumul\u00f3 durante a\u00f1os hasta que Cuadrado y su incansable amigo Luis armados de sus detectores de metales las encontraron y recuperaron. Alejandro dice que no las ha limpiado porque de alguna forma se perder\u00eda la historia que nos cuentan, de derrota, abandono y olvido. En la exposici\u00f3n se muestran algunas armas singulares, como un par se subfusiles ametralladores fabricados en por la industria de guerra de Catalu\u00f1a durante la guerra civil, adem\u00e1s de numerosos ejemplares de granadas de mano de diversas procedencias.<br \/>\nLa otra parte del museo es mucho m\u00e1s entra\u00f1able y est\u00e1 formada por una serie de objetos que forman parte de la vida y la historia de la familia Cuadrado: carros de mano, un cochecito de ni\u00f1o, uno de los veh\u00edculos que usaba su padre,&#8230;carnets y documentos, muebles  prendas de vestir nos llevan a otra \u00e9poca y nos asombran por su magn\u00edfico estado de conservaci\u00f3n.<br \/>\nPor \u00faltimo algunos documentos recopilados por Alejandro como coleccionista y adquiridos o encontrados en su propia casa: publicaciones y carteles de la posguerra, portadas de peri\u00f3dicos.<br \/>\nSiempre me parece meritorio que esta preocupaci\u00f3n por la conservaci\u00f3n de documentaci\u00f3n y patrimonio tenga una iniciativa privada cuando a veces las instituciones p\u00fablicas parecen usar criterios ajenos al mero inter\u00e9s hist\u00f3rico para distribuir los presupuestos. Por eso esperamos que la iniciativa de Alejandro salga adelante y pronto veamos importantes mejoras en su museo.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2888805653\" target=\"_blank\" ><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3051\/2888805653_35384a4008_s.jpg\" border=\"0\" class=\"\"><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2888805611\" target=\"_blank\" ><img decoding=\"async\" src=\"http:\/\/static.flickr.com\/3265\/2888805611_79f42f4263_s.jpg\" border=\"0\" class=\"\"><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2888805559\" target=\"_blank\" ><img decoding=\"async\" src=\"http:\/\/static.flickr.com\/3149\/2888805559_d0c9814b6d_s.jpg\" border=\"0\" class=\"\"><\/a> <a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2889638120\" target=\"_blank\" ><img decoding=\"async\" src=\"http:\/\/static.flickr.com\/3210\/2889638120_81bb72b980_s.jpg\" border=\"0\" class=\"\"><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La semana pasada pude ir a ver el Museo de la Retirada, en Camprod\u00f3n. Cuando se inaugur\u00f3 este verano no pude ir porque estaba fuera de Figueres y le hab\u00eda prometido a Alejandro Cuadrado, su propietario que buscar\u00eda un d\u00eda &hellip; <a href=\"https:\/\/robertopla.net\/blog\/museo-de-la-retirada.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-464","post","type-post","status-publish","format-standard","hentry","category-aerotrastorno"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/464\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}