{"id":470,"date":"2008-09-28T08:33:19","date_gmt":"2008-09-28T06:33:19","guid":{"rendered":"http:\/\/robertopla.net\/blog\/googleblog-para-webmasters.htm"},"modified":"2008-09-28T08:33:19","modified_gmt":"2008-09-28T06:33:19","slug":"googleblog-para-webmasters","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/googleblog-para-webmasters.htm","title":{"rendered":"Google:Blog para webmasters"},"content":{"rendered":"<p>Google acaba de iniciar la publicaci\u00f3n de un <a href=\"http:\/\/googlewebmaster-es.blogspot.com\/\">Blog para webmasters<\/a> en espa\u00f1ol. Cuando escribo estas lineas solo tiene tres anotaciones a pesar de que se inici\u00f3 el 15 de septiembre con una anotaci\u00f3n en la que entre otras cosas se dec\u00eda:<\/p>\n<blockquote><p>La primera de las diez conclusiones a las que ha llegado Google dice: \u00ab<a href=\"http:\/\/www.google.com\/intl\/es\/corporate\/tenthings.html\">Lo m\u00e1s importante es pensar en el usuario<\/a>\u00ab.<br \/>\nEste es uno de los motivos por los que empezamos este blog. Intentaremos manteneros informados sobre todo lo que Google tiene que decir a los webmasters, \u00a1y en espa\u00f1ol!<br \/>\nHablaremos de temas como rastreo, indexaci\u00f3n y organizaci\u00f3n del ranking y adem\u00e1s de las Herramientas para webmasters, Sitemaps y cualquier tipo de preguntas que un webmaster pueda tener.<\/p><\/blockquote>\n<p>L\u00f3gicamente el Blog est\u00e1 alojado en Blogger, el sistema de Blogs propiedad de Google.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google acaba de iniciar la publicaci\u00f3n de un Blog para webmasters en espa\u00f1ol. Cuando escribo estas lineas solo tiene tres anotaciones a pesar de que se inici\u00f3 el 15 de septiembre con una anotaci\u00f3n en la que entre otras cosas &hellip; <a href=\"https:\/\/robertopla.net\/blog\/googleblog-para-webmasters.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-470","post","type-post","status-publish","format-standard","hentry","category-frikilandia"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}