{"id":477,"date":"2008-10-10T23:53:02","date_gmt":"2008-10-10T21:53:02","guid":{"rendered":"http:\/\/robertopla.net\/blog\/el-peni-1958-2008.htm"},"modified":"2008-10-10T23:53:02","modified_gmt":"2008-10-10T21:53:02","slug":"el-peni-1958-2008","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/el-peni-1958-2008.htm","title":{"rendered":"El Pen\u00ed 1958-2008"},"content":{"rendered":"<p>Con motivo del 50 aniversario de la construcci\u00f3n de la base del Pan\u00ed -o Pen\u00ed en catal\u00e1n- se celebran en Roses <a href=\"http:\/\/panical.org\/archivos\/diptic_peni50.pdf\">una serie de actos<\/a>, entre los que figura un ciclo de conferencias que inici\u00f3 el viernes pasado Gep Barris, el archivero de Roses habl\u00e1ndonos de los testimonios sobre la presencia de los americanos a trav\u00e9s de los documentos conservados en el Archivo municipal de Roses y que este pasado viernes continu\u00f3 Marcelino Sempere, Capit\u00e1n de Aviaci\u00f3n, profesor de la Academia general del Aire y Doctor en Historia, sobre \u00abLos tratados de amistad y cooperaci\u00f3n\u00bb.<br \/>\nAmbas conferencias han sido un \u00e9xito de p\u00fablico que ha participado en los interesante coloquios suscitados tras la exposici\u00f3n de los conferenciantes.<br \/>\nEl viernes 10 tambi\u00e9n fue inaugurada en el hall del Teatro Municipal una exposici\u00f3n sobre el mismo tema que recoge bastante material de procedencia americana, mucho del cual se haya en servicio a\u00fan en el EVA-4 la unidad del Ej\u00e9rcito del Aire Espa\u00f1ol que hoy ocupa las instalaciones de Pan\u00ed.<br \/>\nLos actos han sido organizados por la Fundaci\u00f3n Padrosa y el Ayuntamiento de Roses y patrocinados por Prestige Hotels y han contado -como no pod\u00eda se de otra manera- con la colaboraci\u00f3n del Ministerio de Defensa a trav\u00e9s del EVA-4.<\/p>\n<div style=\"text-align:center;\">\n<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/2931965303\/\"><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3027\/2931965303_0b6594d527.jpg\" style=\"border:none;width:450px;height:338px;\" alt=\"Material expuesto\"  title=\"Material expuesto\"\/><\/a><\/p>\n<\/div>\n<p>El pr\u00f3ximo d\u00eda 12 se celebrar\u00e1 en el escuadr\u00f3n un encuentro de veteranos. Hasta el momento hay muchos antiguos soldados y profesionales que han anunciado que vendr\u00edan y lo que m\u00e1s nos preocupa es que puedan formarse atascos de veh\u00edculos en el camino de acceso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del 50 aniversario de la construcci\u00f3n de la base del Pan\u00ed -o Pen\u00ed en catal\u00e1n- se celebran en Roses una serie de actos, entre los que figura un ciclo de conferencias que inici\u00f3 el viernes pasado Gep Barris, &hellip; <a href=\"https:\/\/robertopla.net\/blog\/el-peni-1958-2008.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","hentry","category-rerum-militari"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}