{"id":5384,"date":"2024-12-27T20:48:03","date_gmt":"2024-12-27T19:48:03","guid":{"rendered":"https:\/\/robertopla.net\/blog\/?p=5384"},"modified":"2024-12-28T01:18:10","modified_gmt":"2024-12-28T00:18:10","slug":"tintero-de-viaje","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/tintero-de-viaje.htm","title":{"rendered":"Tintero de viaje"},"content":{"rendered":"<p>En un mensaje que le\u00ed en <a href=\"https:\/\/masto.es\/@rpla\">Mastodon<\/a>, preguntaban si alguien sab\u00eda de frascos para llevar perfume que no se derramen ni tengan p\u00e9rdidas e insist\u00eda mucho en qu\u00e9 no le interesan las opiniones o las indicaciones no constatadas. Como quiz\u00e1s mi respuesta iba a encajar con sus necesidades, decid\u00ed no comentar, pero segu\u00ed las respuestas de la conversaci\u00f3n porque yo me hab\u00eda planteado una pregunta similar para poder viajar con tinta de repuesto para las plumas que recargo desde tintero.<\/p>\n<p>Luego he perd\u00ed la pista del mensaje y con los pocos datos que hab\u00eda guardado y gracias a la ayuda de <a href=\"https:\/\/masto.es\/@asturel@tkz.one\">asturel@tkz.one<\/a> lo he vuelto a encontrar as\u00ed como algunos datos interesantes.<\/p>\n<p>Comprar por internet tiene algunas ventajas y tambi\u00e9n inconvenientes. Uno de ellos es no ver y tocar el producto antes de comprar. Las fotos, a veces, no dan idea incluso de aspectos muy concretos, como el tama\u00f1o. As\u00ed que sobre otras cosas como la estanqueidad suele ser dif\u00edcil hacerse una idea.<br \/>\nTuve que resolver ese problema para transportar tinta, un l\u00edquido con el que los experimentos son m\u00e1s arriesgados que con el perfume.<br \/>\nHay muchos envases que \u00abparecen\u00bb o se anuncian como herm\u00e9ticos, pero no es lo mismo el hermetismo necesario en un tintero de sobremesa que el que ha de viajar en una maleta sujeta a las volteretas propias del trasiego en un aeropuerto.<br \/>\nCuando prepar\u00e9 mi viaje a Argentina tuve en cuenta que dada la duraci\u00f3n del viaje, tendr\u00eda que pensar en reponer la tinta de las plumas.<br \/>\nPara las plumas de dibujo eleg\u00ed llevar cartuchos. Por suerte hay cartuchos de la misma tinta que normalmente uso de tintero, <a href=\"https:\/\/vpiera.com\/es\/tintero-platinum-pigment-ink-60-ml-color-negro\">Platinum \u00abCarbon Ink\u00bb<\/a>. Mi pluma es una <a href=\"https:\/\/www.pwakkerman.com\/es\/pluma-estilogr-fica-sailor-fude-de-mannen-caligraf-a-azul-(c)10-0212-740\/info\">Sailor \u00abProfit\u00bb<\/a> y por desgracia, no es compatible con esos cartuchos.<br \/>\nLo solucion\u00e9 a\u00f1adiendo al equipaje una pluma <a href=\"https:\/\/www.flickr.com\/photos\/fotero\/52224985498\">Platinum \u00abpreppy\u00bb<\/a> sin estrenar, compatible con los cartuchos. Cuando se acabo la tinta de la Profit abr\u00ed el cartucho para colocarlo en la \u00abpreppy\u00bb y le saqu\u00e9 tinta con una jeringuilla para rellenar el convertidor de la otra. El sistema funcion\u00f3, no tuve problemas con la tinta negra y us\u00e9 las dos plumas (diferentes plumines) para dibujar.<br \/>\nPara escribir llevaba una <a href=\"https:\/\/estilograficasviena.com\/tienda\/prefounte\/\">Platinum \u00abPrefounte\u00bb<\/a> entintada con tinta <a href=\"https:\/\/www.jacquesherbin.com\/produit\/bleu-myosotis\/\">Jacques Herbin \u00abBlue Myosotis\u00bb<\/a>. Compr\u00e9 hace un tiempo una botella de medio litro a un precio fant\u00e1stico, pero necesitaba algo m\u00e1s peque\u00f1o para los viajes.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" style=\"border: none; width: 580px; height: 267px;\" title=\"Cuaderno\" src=\"https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/frascos_c33_900.jpg\" alt=\"Cuaderno\" \/><\/p>\n<p>Estudi\u00e9 el tema con varias pruebas de las que luego guard\u00e9 testimonio en un peque\u00f1o cuaderno (12x12cm) que uso para notas, ideas y dibujos y que es una especie de \u00abcuaderno de temas comunes\u00bb m\u00e1s que un cuaderno de bocetos como los otros que uso para dibujar.<br \/>\nLos botes de mermelada diminutos son curiosos. Al cerrarlos con mermelada caliente, se ponen al rev\u00e9s y al enfriarse, la contracci\u00f3n del aire en su interior hace el vac\u00edo y sella la tapa. Pero cerrados en seco su estanqueidad puede no ser perfecta y cuando los he usado para transportar agua para las acuarelas me han dado problemas, especialmente si han sido reutilizados varias veces.<br \/>\nLos tubos de muestras los uso para enviar tinta en intercambios con otros aficionados, pero siempre los sello con cinta adhesiva y los envuelvo en papel absorbente para prevenir alguna posible p\u00e9rdida. Me parecieron peque\u00f1os.<br \/>\nEl siguiente frasco lo encontr\u00e9 un bazar y compr\u00e9 una caja de 20 a buen precio. Los uso a veces para guardar restos de mezclas de tinta, pero la tapa es poco herm\u00e9tica ya que no dispone de ning\u00fan tipo de junta de estanqueidad.<br \/>\nPor \u00faltimo ten\u00eda un peque\u00f1o frasco procedente de la cocina y que hab\u00eda contenido esencia de vainilla o alguna cosa similar. El tap\u00f3n de pl\u00e1stico entraba a presi\u00f3n y me pareci\u00f3 seguro.<br \/>\nDespu\u00e9s de un concienzudo lavado hizo conmigo -en cabina- el viaje a Buenos Aires y regres\u00f3 sin incidentes. Y luego me acompa\u00f1\u00f3 a Murcia. He recargado un par de veces un cartucho universal que uso con el adaptador en la Prefounte y a\u00fan queda tinta.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5388\" src=\"https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/frasco01.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/frasco01.jpg 799w, https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/frasco01-300x200.jpg 300w, https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/frasco01-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Yo no ten\u00eda ni idea de donde encontrar m\u00e1s frascos como este. Siguiendo la pista del mensaje mencionado, encontr\u00e9 algunas respuestas como la de\u00a0 <a class=\"detailed-status__display-name\" style=\"cursor: pointer !important; user-select: none !important;\" href=\"https:\/\/masto.es\/@NebelRebel@xarxa.cloud\" data-hover-card-account=\"111664945303308110\"><span class=\"display-name\"><span class=\"display-name__account\">NebelRebel <\/span><\/span><\/a>que lo mencionaban como \u00abviales\u00bb y\u00a0 la tienda que los vende en Barcelona, <a href=\"https:\/\/www.torrerovidre.com\/frasquitos-de-vidrio.html\">Torrero Vidre<\/a> con lo que finalmente mi curiosidad me ha llevado a una soluci\u00f3n concreta y pr\u00e1ctica: Este es el tintero de viaje id\u00f3neo y la comparto con vosotros, esperado que tambi\u00e9n os sea de utilidad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5389\" src=\"https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/gra_familia-3_5.jpg\" alt=\"\" width=\"253\" height=\"253\" srcset=\"https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/gra_familia-3_5.jpg 253w, https:\/\/robertopla.net\/blog\/wp-content\/uploads\/2024\/11\/gra_familia-3_5-150x150.jpg 150w\" sizes=\"auto, (max-width: 253px) 100vw, 253px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llevar tinta para recargar las plumas cuando vas de viaje puede ser un problema si no cuentas con el recipiente adecuado.  <a href=\"https:\/\/robertopla.net\/blog\/tintero-de-viaje.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[476],"tags":[95,430,622,431,357],"class_list":["post-5384","post","type-post","status-publish","format-standard","hentry","category-dibujando-letras","tag-dibujo","tag-estilografica","tag-mastodon","tag-tinta","tag-viaje"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/5384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=5384"}],"version-history":[{"count":6,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/5384\/revisions"}],"predecessor-version":[{"id":5409,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/5384\/revisions\/5409"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=5384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=5384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=5384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}