{"id":545,"date":"2009-02-26T23:15:38","date_gmt":"2009-02-26T21:15:38","guid":{"rendered":"http:\/\/robertopla.net\/blog\/el-campo-de-aviacion-de-la-senia.htm"},"modified":"2009-02-26T23:15:38","modified_gmt":"2009-02-26T21:15:38","slug":"el-campo-de-aviacion-de-la-senia","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/el-campo-de-aviacion-de-la-senia.htm","title":{"rendered":"El campo de aviaci\u00f3n de la S\u00e9nia"},"content":{"rendered":"<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/3313776942\/\"><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3388\/3313776942_97d3b9eb0a_m.jpg\" style=\"border-style: none; float: left; position: relative; left: 0px; padding-right: 10px; padding-bottom: 10px; padding-top: 10px;width:167px;height:240px;\"  alt=\"Portada\"  title=\"Portada\"\/><\/a>Heribert Garc\u00eda Esteller nos presenta una segunda edici\u00f3n, muy mejorada y ampliada de un libro que a pesar de su car\u00e1cter artesanal supone ya uno de los hitos imprescindibles en la biblioteca de cualquier aficionado. De  \u00abL&#8217;aer\u00f2drom de la S\u00e9nia 1937-39\u00bb hay que decir en primer lugar que es un libro biling\u00fce que tiene sus textos en catal\u00e1n y castellano, algo que agradecer\u00e1n sin duda muchos estudiosos de nuestra guerra civil que ven como se publican en Catalu\u00f1a mucho e interesantes trabajos de historia local relacionados con ese periodo pero que al hacerlo solo en catal\u00e1n limitan su difusi\u00f3n y dificultan el acceso a una informaci\u00f3n muy interesante y necesaria para comprender todas las facetas del conflicto.<\/p>\n<p>Como en otras ocasiones, adem\u00e1s de los apoyos oficiales, la pieza clave es el empe\u00f1o del autor hombre apasionado del tema que con paciencia y tes\u00f3n ha ido acumulando cada brizna de conocimiento publicada, conocida o ignota sobre uno de los campos de aviaci\u00f3n m\u00e1s emblem\u00e1ticos de la guerra civil por haber constituido primero punta de lanza e instalaci\u00f3n mod\u00e9lica de las Fuerzas A\u00e9reas Republicanas en cuanto a campos de guerra y m\u00e1s tarde base de la Legi\u00f3n C\u00f3ndor en sus operaciones durante la campa\u00f1a de Catalu\u00f1a. El campo fue asimismo protagonista de un ataque por parte de la aviaci\u00f3n republicana, conocido por el testimonio del <a href=\"http:\/\/adar.es\/index\/index.php?option=com_content&#038;task=view&#038;id=50&#038;Itemid=#17\">Rafael Ballester Linares<\/a>, tripulante de uno de los aviones republicanos atacantes que fue abatido y sobrevivi\u00f3 al saltar sobre el campo, siendo hecho prisionero por los alemanes.<\/p>\n<p>La clave del libro que hoy analizamos son los documentos. Se trata sin duda de la mayor colecci\u00f3n de fotograf\u00edas publicadas sobre el campo de la S\u00e9nia, muchas de ellas de la colecci\u00f3n particular del autor que las ha atesorado con paciencia, mucho esfuerzo y muchas veces con un importante dispendio econ\u00f3mico. Por otra parte fotograf\u00edas procedentes de otros archivos particulares de estudiosos uy coleccionistas a los que hay que agradecer su colaboraci\u00f3n en este libro. Seg\u00fan el propio autor, alrededor de un veinte por ciento de las fotograf\u00edas de esta edici\u00f3n no aparecieron en la edici\u00f3n anterior. Como ocurre muchas veces la primera edici\u00f3n sirve de bander\u00edn de reclamo para que muchos testigos y propietarios de documentaci\u00f3n se pongan en contacto con el autor, al que tenemos que agradecer que no se haya guardado este ap\u00e9ndice y lo haya integrado en esta nueva edici\u00f3n, realizada con el apoyo del Ayuntamiento de la S\u00e9nia y la Generalitat de Catalunya que han dado su apoyo tambi\u00e9n al proyecto de musealizaci\u00f3n del <a href=\"http:\/\/www.campaviaciolasenia.cat\/\">campo de aviaci\u00f3n<\/a>.<\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/3312950159\/\"><img decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3361\/3312950159_0f70db5087.jpg\" style=\"border-style: none;width:450px;height:338px;\" alt=\"El autor\"  title=\"El autor\"\/><\/a><\/\n\nEl viernes d\u00eda 6 de febrero de 2009, se realiz\u00f3 la presentaci\u00f3n del libro en el sal\u00f3n de actos de la Fundaci\u00f3n Caja Vinar\u00f2s de la Plaza Cardenal Taranc\u00f3n de Vinar\u00f2s. La presentaci\u00f3n corri\u00f3 a cargo del autor, que qued\u00f3 muy satisfecho por la asistencia de p\u00fablico y la acogida del libro por parte de los vinarocenses. Durante la presentaci\u00f3n se proyect\u00f3 un audiovisual d\u00f3nde se pod\u00edan contemplar las valiosas fotograf\u00edas que el autor ha ido recopilando del periodo de tiempo en que el campo de aviaci\u00f3n de la S\u00e9nia estuvo operativo. d\u00edas m\u00e1s tarde, el 24 de febrero el libro se present\u00f3 en Tarragona. La librer\u00eda La Rambla fue el escenario donde el autor y el profesor Josep S\u00e1nchez Cervell\u00f3 presentaron al numeroso p\u00fablico tarraconense esta obra sobre la guerra civil en la S\u00e9nia.\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heribert Garc\u00eda Esteller nos presenta una segunda edici\u00f3n, muy mejorada y ampliada del libro \u00abL&#8217;aer\u00f2drom de la S\u00e9nia 1937-39\u00bb  <a href=\"https:\/\/robertopla.net\/blog\/el-campo-de-aviacion-de-la-senia.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[43,144,166,197,423,235],"class_list":["post-545","post","type-post","status-publish","format-standard","hentry","category-libros","tag-aviacion","tag-gce","tag-historia","tag-legion-condor","tag-libros","tag-militar"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}