{"id":578,"date":"2009-05-09T10:12:42","date_gmt":"2009-05-09T08:12:42","guid":{"rendered":"http:\/\/robertopla.net\/blog\/gafas-para-leer.htm"},"modified":"2009-05-09T10:12:42","modified_gmt":"2009-05-09T08:12:42","slug":"gafas-para-leer","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/gafas-para-leer.htm","title":{"rendered":"Gafas para leer"},"content":{"rendered":"<p>Pues si, la presbicia galopante me afecta <a href=\"http:\/\/robertopla.net\/blog\/el-infierno.htm\">hace unos a\u00f1os<\/a>. Durante un tiempo he intentado esquivarla y forzar un poco la vista para que no se acomode a las parihuelas de las lentes, pero despu\u00e9s de un tiempo no me ha quedado m\u00e1s remedio que acudir a las gafas para leer.<br \/>\nLas primeras fueron una aut\u00e9ntica pesadez. Debido a mi ya conocido y natural despiste me las iba dejando por todos los sitios, me mareaba al levantar la vista sin acordarme de quit\u00e1rmelas y no las ten\u00eda a mano cuando las necesitaba.<br \/>\nFinalmente decid\u00ed que, como los bol\u00edgrafos, ten\u00eda que tener gafas repartidas por todos mis escritorios habituales para no encontrarme en ninguna ocasi\u00f3n falto de ellas. Entonces ya usaba gafas &#8216;gen\u00e9ricas&#8217; compradas en farmacias con graduaci\u00f3n est\u00e1ndar de media en media dioptr\u00eda. Pero el gran descubrimiento fueron las gafas de supermercado. En LIDL pusieron de oferta unas gafas a 4 euros. A ese precio no pod\u00eda encontrarme sin gafas en ninguna situaci\u00f3n y compr\u00e9 unas para el caj\u00f3n de casa y otras para el del despacho, aunque podr\u00eda haber comprado unas para cada chaqueta y as\u00ed habr\u00eda asegurado m\u00e1s el tiro.<br \/>\nEl otro d\u00eda cuando guardaba las del despacho en el caj\u00f3n correspondiente, les quit\u00e9 una etiqueta y me d\u00ed cuenta de que llevaba algo escrito. Los fabricantes de aquellas gafas deben ser est\u00fapidos o tener muy mala leche, porque si me hubiera dado cuenta en el supermercado no las habr\u00eda comprado. El tama\u00f1o de la letra es de medio mil\u00edmetro. Cada linea ocupa apenas un mil\u00edmetro. Me puse las gafas y no pod\u00eda leerlo, tuve que recurrir a una potente lupa que tengo en la mesa. Me parece una promoci\u00f3n muy desacertada del producto. Lo astuto habr\u00eda sido poner el mensaje en una letra f\u00e1cilmente legible con las gafas, al hacerlo el cliente habr\u00eda pensado: \u00a1que buenas que son!. Hay que decir que las gafas con m\u00e1s dioptr\u00edas no eran m\u00e1s caras: esta podr\u00eda haber sido la \u00fanica explicaci\u00f3n l\u00f3gica.<br \/>\nPara hacerse idea del dislate, esa letra no podr\u00eda representarse en la pantalla a su tama\u00f1o natural ya que si una pulgada son 25,4 mil\u00edmetros y un punto de la pantalla es 1\/72 de pulgada, llegamos f\u00e1cilmente a la conclusi\u00f3n de que un punto mide 0,3528 mil\u00edmetros, \u00f3 seg\u00fan suele decir la publicidad de los monitores, 0,28 mm. Aunque fueran 0,26 mm. en un monitor de calidad excelent\u00edsima, solo contar\u00edamos con dos puntos de alto para representar cada letra, algo de todo punto de vista insuficiente incluso para los que disfruten de vista de lince.<\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/3531535701\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2041\/3531535701_69592ae285.jpg\" style=\"border:none;width:450px;height:300px;\" alt=\"La etiqueta\" title=\"La etiqueta\" \/><\/a><\/p>\n<p><strong>Actualizaci\u00f3n 15\/05\/2009:<\/strong> Hoy he a\u00f1adido esta foto de la etiqueta que ten\u00eda hecha desde hace ocho d\u00edas. Por alguna raz\u00f3n los art\u00edculos del blog se me est\u00e1n retrasando, tengo que ponerme las pilas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues si, la presbicia galopante me afecta hace unos a\u00f1os. Durante un tiempo he intentado esquivarla y forzar un poco la vista para que no se acomode a las parihuelas de las lentes, pero despu\u00e9s de un tiempo no me &hellip; <a href=\"https:\/\/robertopla.net\/blog\/gafas-para-leer.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-578","post","type-post","status-publish","format-standard","hentry","category-fugaces"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/578\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}