{"id":623,"date":"2009-09-02T23:42:56","date_gmt":"2009-09-02T21:42:56","guid":{"rendered":"http:\/\/robertopla.net\/blog\/rotarios-y-leones.htm"},"modified":"2009-09-02T23:42:56","modified_gmt":"2009-09-02T21:42:56","slug":"rotarios-y-leones","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/rotarios-y-leones.htm","title":{"rendered":"Rotarios y Leones"},"content":{"rendered":"<p>El jueves de la semana pasada tuve ocasi\u00f3n de asistir a una de las reuniones semanales del <a href=\"http:\/\/www.rotary.org\/es\/\">Club Rotary Internacional<\/a>, exactamente a la del c\u00edrculo de Roses. Cuando se habla del Rotary estoy seguro que hay mucha gente que tiene una idea vaga de que se trata o incluso recuerda haber visto un letrero a la entrada de alguna poblaci\u00f3n se\u00f1alando el d\u00eda de las reuniones semanales, una versi\u00f3n laica de los letreros que indican las horas de las misas en algunos pueblos.<br \/>\nCon la desconfianza que nos caracteriza hacia lo desconocido, no falta quien sin asomo de duda tacha de &#8216;sectario&#8217;, &#8216;elitista&#8217; o &#8216;de car\u00e1cter mas\u00f3nico&#8217; a este grupo, que comparte los calificativos con otra organizaci\u00f3n similar, el <a href=\"http:\/\/www.lionsclubs.org\/SP\/index.php\">Club Internacional de los Leones<\/a>. Hay que decir tambi\u00e9n que es frecuente que las personas que hacen estos comentarios no conozcan en absoluto las organizaciones ni a ninguno de sus miembros y por ello deben ser catalogados como rumores de nula credibilidad.<br \/>\nPero \u00bfQue son el Club Rotary o el Club de los Leones?. Lo primero que tengo que advertir, antes de empezar a expresar mis opiniones es que yo no soy miembro de ninguna de las dos organizaciones ni entra en mis planes ingresar en ninguna. Mis opiniones est\u00e1n fundadas en lo que amigos y conocidos, miembros de las mismas me han contado sobre ellas y en la informaci\u00f3n que puede encontrarse sobre las mismas en internet.<\/p>\n<p style=\"text-align:center\"><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/rotary.jpg\" alt=\"Rotary\" \/><br \/>\n<img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/leones.jpg\" alt=\"Leones\" \/><\/p>\n<p>Para hacer una aproximaci\u00f3n r\u00e1pida dir\u00eda que ambas organizaciones son lo que hoy conocemos como una <a href=\"http:\/\/es.wikipedia.org\/wiki\/Organizaci%C3%B3n_no_gubernamental\">ONG<\/a>. Lo que pasa es que al datar su fundaci\u00f3n de principios del Siglo XX su \u00abimagen\u00bb no cuadra con algunas de las ONG m\u00e1s modernas. Por otra parte ambas organizaciones, sin menospreciar los proyectos que puedan promover a nivel mundial, intentan mejorar la situaci\u00f3n sobre todo en su propio entorno.<br \/>\nSon sociedades filantr\u00f3picas, sin que ello implique una aportaci\u00f3n dineraria de sus socios, sino que estos procuran mediante campa\u00f1as o proyectos la obtenci\u00f3n de fondos aportando, eso si, su esfuerzo y su trabajo organizativo.<br \/>\nLa diferencia entre la filantrop\u00eda y la caridad es que mientras que la primera es una generosidad movida por el amor al g\u00e9nero humano, la segunda es una virtud teologal, porque ambas asociaciones, dentro del respeto a las creencias de sus miembros son de car\u00e1cter completamente laico.<br \/>\nTampoco es de extra\u00f1ar que hayan sido acusadas en ciertas ocasiones de ser de car\u00e1cter mas\u00f3nico, un adjetivo que en una \u00e9poca se aplicaba a todo aquello que no fuera de inspiraci\u00f3n clerical.  En realidad los fundadores del <a href=\"http:\/\/es.wikipedia.org\/wiki\/Rotary_International\">Rotary<\/a> eran masones norteamericanos, lo cual no tiene nada de extra\u00f1o ya que la filantrop\u00eda es sin duda uno de los principios respetados por los masones cuyo esp\u00edritu de servicio est\u00e1 tambi\u00e9n en los principios del Rotary.<br \/>\nPor su parte el <a href=\"http:\/\/es.wikipedia.org\/wiki\/Club_de_Leones\">Club de los Leones<\/a> se fund\u00f3 tambi\u00e9n en Chicago, doce a\u00f1os despu\u00e9s del Rotary por el empresario Melvin Jones. Su obra social, promovida por los Clubs de Leones se extiende por todo el mundo y por ejemplo en Estados Unidos, donde no existe una organizaci\u00f3n como la <a href=\"http:\/\/www.once.es\/\">ONCE<\/a> es conocido su apoyo a los invidentes proporcionando perros adiestrados como guias. Otra se\u00f1alada actuaci\u00f3n del leonismo fu\u00e9 la popularizaci\u00f3n del bast\u00f3n blanco para los invidentes, inventado por el argentino <a href=\"http:\/\/es.wikipedia.org\/wiki\/Bast%C3%B3n_blanco\">Jos\u00e9 Fall\u00f3tico<\/a>. En George Benham, presidente del Club de Leones de Illinois, propuso para uso de los discapacitados visuales un bast\u00f3n blanco con extremo inferior rojo, a fin de que se les otorgue prioridad de paso.<br \/>\nEn definitiva, ambas organizaciones re\u00fanen a personas voluntarias, con esp\u00edritu de servicio a los dem\u00e1s y dispuestas a dedicar una parte de su tiempo a mejorar la sociedad. Su cohesi\u00f3n se basa en la amistad entre sus miembros y su actividad se se ordena a trav\u00e9s de reuniones que en el Rotary son semanales y en los clubes de Leones mensuales, (con reuniones quincenales de las juntas directivas). Si alguien me preguntase en cual de ambas organizaciones le aconsejar\u00eda ingresar, mi respuesta sin ning\u00fan g\u00e9nero de dudas seria: \u00ab<em>un\u00e1se al grupo que tenga m\u00e1s cerca y en el que est\u00e9n sus amigos<\/em>\u00ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves de la semana pasada tuve ocasi\u00f3n de asistir a una de las reuniones semanales del Club Rotary Internacional, exactamente a la del c\u00edrculo de Roses. Cuando se habla del Rotary estoy seguro que hay mucha gente que tiene &hellip; <a href=\"https:\/\/robertopla.net\/blog\/rotarios-y-leones.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-623","post","type-post","status-publish","format-standard","hentry","category-fugaces"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=623"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/623\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}