{"id":625,"date":"2009-08-31T13:39:03","date_gmt":"2009-08-31T11:39:03","guid":{"rendered":"http:\/\/robertopla.net\/blog\/pa-amb-xocolata.htm"},"modified":"2009-08-31T13:39:03","modified_gmt":"2009-08-31T11:39:03","slug":"pa-amb-xocolata","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/pa-amb-xocolata.htm","title":{"rendered":"Pa amb Xocolata"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/robertopla.net\/blog\/img\/paxocolata.jpg\" alt=\"Portada\" title=\"Portada\" style=\"border-style: none; float: left; position: relative; left: 0px; padding-right: 10px; padding-bottom: 10px; padding-top: 10px;\"\/>Cuando apareci\u00f3 el libro, la autora me envi\u00f3 un correo para avisarme. Hab\u00edamos intercambiado algunos mensajes sobre temas aeron\u00e1uticos detalles que ella necesitaba para documentar el libro. Yo se los busqu\u00e9 y puse una condici\u00f3n: no ser mencionado en absoluto en los agradecimientos del libro. Esta condici\u00f3n, que puede parecer extra\u00f1a procede de la experiencia obtenida en la lectura un libro de un afamado autor y los agradecimientos por el asesoramiento en temas aeron\u00e1uticos de uno de los mayores especialistas espa\u00f1oles en temas de la Legi\u00f3n Condor y la Luftwaffe que vio seriamente amenazado su cr\u00e9dito de erudito debido a que su docto asesoramiento fue completamente ignorado por el autor, que en su libro hac\u00eda volar al Stuka a velocidades pr\u00f3ximas a la barrera del sonido&#8230;<br \/>\nYo no tengo una fama de erudito que proteger, pero quisiera mantener limpio el solar donde edificarla si llega el caso. Lo cierto es que no compr\u00e9 el libro porque no ten\u00eda tiempo de leerlo, pero unos meses despu\u00e9s lo oje\u00e9 por curiosidad en la <a href=\"http:\/\/libros.fnac.es\/a310957\/Teresa-Roig-Pa-amb-xocolata?OrderInSession=1&#038;Mn=-1&#038;SID=174d060e-7bde-bae0-c439-1986c38ea7e6&#038;Origin=FnacAff&#038;Ra=-1&#038;To=0&#038;Nu=1&#038;UID=0E96E96AB-560E-3B36-2DE4-368DC3854C2B&#038;Fr=0\">fnac<\/a> y \u00a1Oh, sorpresa! en la p\u00e1gina de agradecimientos dec\u00eda: \u00ab<em>A Roberto, de la Asociaci\u00f3n Aire<\/em>\u00ab. No me quedaba m\u00e1s remedio que leer el libro para ver como hab\u00eda sido tratada mi humilde aportaci\u00f3n al mismo.<br \/>\nHe tardado todav\u00eda unos meses en poderlo leer, pero tengo que reconocer que solo me ha costado dos d\u00edas leerlo enterito, lo cual ya es un punto a favor del libro. Y en el aspecto aeron\u00e1utico es bastante prudente, quiz\u00e1s por el hecho de que no incluye muchos detalles, de forma que a sus \u00abgracias\u00bb yo deber\u00eda responder con toda sinceridad y exactitud \u00abde nada\u00bb. Creo que los fallos que pueden encontrarse en relaci\u00f3n a cuestiones aeron\u00e1uticas son fallos m\u00e1s bien de sentido com\u00fan. No se entiende que despu\u00e9s de estrellarse un <a href=\"http:\/\/es.wikipedia.org\/wiki\/Fiat_CR-32\">Fiat CR-32<\/a> en un bosque, su piloto salga con heridas pero recobre por si solo la consciencia y el aparato se almacene en un granero para despu\u00e9s de dos a\u00f1os ser reconstruido por una sola persona&#8230;<br \/>\nEl libro presenta dos tramas entrelazadas. Una de car\u00e1cter humano nos cuenta la vida de una familia y un pueblo durante la guerra civil. La otra pretende plantear una intriga que aporte tensi\u00f3n y emoci\u00f3n a la trama. Aunque no lo consigue y est\u00e1 plagada de inconsistencias y hechos dif\u00edcilmente entendibles o cre\u00edbles, hay que decir que su m\u00e9rito es no estropear la otra vertiente del libro. De hecho, el protagonista principal de la segunda trama, el piloto caido en en pueblo es un componente casi fundamental de la trama humana. El final del libro es una concesi\u00f3n prescindible a la actualidad y lo &#8216;pol\u00edticamente correcto&#8217; que no aporta gran cosa, salvo un final discreto.<br \/>\nYo creo que la autora necesita la oportunidad de escribir un libro sin la presi\u00f3n comercial de la publicaci\u00f3n. Muestra una prosa muy agradable de leer que introduce al lector plenamente en el mundo de un peque\u00f1o pueblo de L\u00e9rida y capta perfectamente la esencia que transporta al lector a las escenas, el libro est\u00e1 bien documentado en los aspectos hist\u00f3ricos -se adivinan muchas conversaciones con gente mayor- pero fracasa completamente cuando su pluma se pone al servicio de la industria del libro en lugar de servir a la literatura. Un vocabulario y una redacci\u00f3n cuidada como esta no deber\u00eda mezclarse con argumentos propios de novelas de veinte c\u00e9ntimos.<br \/>\nCon todos sus fallos, tengo que decir que he disfrutado de la lectura del libro y que puedo recomendarlo, recordando que est\u00e1 escrito en catal\u00e1n y que no s\u00e9 si hay planes de publicarlo en castellano. Tambi\u00e9n tengo que decir que a pesar de nuestro pacto, puedo perdonar a Teresa su menci\u00f3n de mi nombre, debido a su prudencia a la hora de entrar en el proceloso mundo de los detalles t\u00e9cnicos y agradecer sin embargo su detalle al recoger la nimia aportaci\u00f3n que nuestro intercambio de mensajes pudiera aportarle, de sobras compensada por el placer de intercambiar ideas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando apareci\u00f3 el libro, la autora me envi\u00f3 un correo para avisarme. Hab\u00edamos intercambiado algunos mensajes sobre temas aeron\u00e1uticos detalles que ella necesitaba para documentar el libro. Yo se los busqu\u00e9 y puse una condici\u00f3n: no ser mencionado en absoluto &hellip; <a href=\"https:\/\/robertopla.net\/blog\/pa-amb-xocolata.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}