{"id":664,"date":"2009-11-23T23:59:23","date_gmt":"2009-11-23T21:59:23","guid":{"rendered":"http:\/\/robertopla.net\/blog\/viaducto-de-millau.htm"},"modified":"2009-11-23T23:59:23","modified_gmt":"2009-11-23T21:59:23","slug":"viaducto-de-millau","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/viaducto-de-millau.htm","title":{"rendered":"Viaducto de Millau"},"content":{"rendered":"<p>El puente <a href=\"http:\/\/www.microsiervos.com\/archivo\/tecnologia\/puente-mas-alto-mundo.html\">m\u00e1s alto del mundo<\/a> tiene 343 metros de alto y est\u00e1 a 260 kil\u00f3metros de mi casa. Saber una cosa as\u00ed y no plantearse ir a verlo manifiesta no solo poco inter\u00e9s por la ingenier\u00eda, sino escasa curiosidad por el mundo en general.<br \/>\nAs\u00ed que, un domingo, un coche y unos amigos eran los \u00fanicos elementos sino necesarios, si al menos aconsejables para preparar una excursi\u00f3n en la que el tiempo meteorol\u00f3gico nos acompa\u00f1\u00f3 para que el asombro fuera completo: noviembre, sol y paisaje.<br \/>\nLlegando al <a href=\"http:\/\/www.tourisme-aveyron.com\/es\/aveyron\/decouverte\/viaduc_de_millau.php\">viaducto de Millau<\/a> desde el sur por la A75, decidimos atravesar el puente y detenernos en el \u00e1rea de informaci\u00f3n donde hay una tienda de recuerdos y punto de informaci\u00f3n en una edificaci\u00f3n singular y desde donde se puede acceder andando a un mirador desde el que la visi\u00f3n del puente es espectacular aunque en las primeras horas de la tarde el sol ya casi nos presentaba un contraluz que dificult\u00f3 un poco las fotos.<\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/4127859386\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2562\/4127859386_63c1dcb6c7.jpg\" style=\"border:none; width:450px;height:146px;\" alt=\"viaducto de Millau\" title=\"viaducto de Millau\" \/><\/a><\/p>\n<p>Del puente nos fuimos corriendo a buscar un restaurante porque en Francia las dos de la tarde es muy tarde para comer. el primero que encontramos fu\u00e9 el Restaurante &#8216;La Tour&#8217; a la entrada de Millau y alli recalamos para dar cuenta de una comida abundante y a un precio razonable.<br \/>\nPor la tarde recorrimos la zona. Primero otro de los miradores del puente, <a href=\"http:\/\/maps.google.es\/maps?q=Millau&#038;oe=utf-8&#038;safe=active&#038;ie=UTF8&#038;hq=&#038;gl=es&#038;ei=CtYLS5zXOJ_SjAe619TZAw&#038;ved=0CA8Q8gEwAA&#038;ll=44.088078,3.052311&#038;spn=0.054375,0.110378&#038;z=13\">en el camino de Brumas<\/a>, saliendo de Creissels por la D992 a la derecha y hasta m\u00e1s arriba del punto desde donde se lanzan los practicantes del Parapente.<br \/>\nMas tarde pasamos por <a href=\"http:\/\/www.aveyron.com\/tourisme\/plusbx\/peyre_plubo.html\">Peyre<\/a>, un pueblo precioso y por Roquefort-sur-Soulzon el pueblo que da nombre al <a href=\"http:\/\/es.wikipedia.org\/wiki\/Queso_roquefort\">m\u00e1s famoso de los quesos azules<\/a>, aunque a mi me gusta m\u00e1s el italiano <a href=\"http:\/\/es.wikipedia.org\/wiki\/Gorgonzola\">Gorgonzola<\/a>.<\/p>\n<p><strong>Nota 25\/11\/2009:<\/strong> Mariona me corrige. No es el punte &#8216;<em>m\u00e1s grande<\/em>&#8216; sino el &#8216;<em>m\u00e1s alto<\/em>&#8216;. Es verdad. La mayor altura en los pilares y la mayor altura en la pasarela, en la categor\u00eda de puentes para vehiculos ya que hay un puente que tiene la pasarela algo m\u00e1s alta, pero es de peatones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El puente m\u00e1s alto del mundo tiene 343 metros de alto y est\u00e1 a 260 kil\u00f3metros de mi casa. Saber una cosa as\u00ed y no plantearse ir a verlo manifiesta no solo poco inter\u00e9s por la ingenier\u00eda, sino escasa curiosidad &hellip; <a href=\"https:\/\/robertopla.net\/blog\/viaducto-de-millau.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-664","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/664\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}