{"id":701,"date":"2010-02-06T22:52:13","date_gmt":"2010-02-06T21:52:13","guid":{"rendered":"http:\/\/robertopla.net\/blog\/plane-spotters-fotografiando-aviones.htm"},"modified":"2010-02-06T22:52:13","modified_gmt":"2010-02-06T21:52:13","slug":"plane-spotters-fotografiando-aviones","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/plane-spotters-fotografiando-aviones.htm","title":{"rendered":"Plane Spotters, Fotografiando aviones"},"content":{"rendered":"<p><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/3935102279\/\" ><img decoding=\"async\" src=\"http:\/\/farm5.static.flickr.com\/4072\/4295687148_75127e633b_m.jpg\" style=\"border: medium none ; margin: 0px 8px 8px 0px; width: 170px; height:240px; float: left;\" alt=\"Cartel Anunciador\" title=\"Cartel Anunciador\"><\/a>El pasado d\u00eda 5 se inaugur\u00f3 en Albacete una exposici\u00f3n fotogr\u00e1fica organizada por la Asociaci\u00f3n Aire y patrocinada por El Corte Ingl\u00e9s y Eurocopter que pretende ofrecer una aproximaci\u00f3n al mundo de los entusiastas de la aviaci\u00f3n m\u00e1s all\u00e1 de los t\u00f3picos.<br \/>\nLa exposici\u00f3n se ha hecho aprovechando parte del material de la la exposici\u00f3n <a href=\"http:\/\/www.microsiervos.com\/archivo\/fotografia\/expo-planespotters.html\">\u00abPlane spotters: la vuelta al mundo en aeropuertos\u00bb<\/a> que se hizo en el aeropuerto de M\u00e1laga con el patrocinio de Aena, Aire, la revista Aviaci\u00f3n Comercial y la Asociaci\u00f3n de Amigos del Museo del Aeropuerto de M\u00e1laga y que ya naci\u00f3 con vocaci\u00f3n itinerante.<br \/>\nComponen la exposici\u00f3n una serie de fotograf\u00edas en papel de socios de Aire y de dos fot\u00f3grafos locales invitados. Adem\u00e1s, otras fotograf\u00edas pueden verse en una pantalla. A la inauguraci\u00f3n asistieron autoridades locales, los miembros de la Junta Directiva y otros socios de Aire y numerosos representantes de la prensa que se ha hecho un amplio eco de la exposici\u00f3n, que esperamos podr\u00e1 verse en otras ciudades de Espa\u00f1a.<br \/>\nMi modesta aportaci\u00f3n al evento fue un texto que se ha incluido en uno de los folletos que acompa\u00f1an a la exposici\u00f3n y que incluyo a continuaci\u00f3n.<\/p>\n<p><strong>\u00bfEres un spotter y no lo sabes?<\/strong><\/p>\n<p>&iquest;Alguna vez, al pasar un avi&oacute;n has levantado la vista y has pensado que te gustar&iacute;a saber de donde viene, a donde va, que modelo de avi&oacute;n es o simplemente te ha maravillado que una maquina pueda volar? <\/p>\n<p>La curiosidad es una caracter&iacute;stica de la naturaleza humana que nos hace interesarnos por lo desconocido, lo misterioso y lo bello. A muchas personas les ha llevado a las cabeceras de las pistas o la proximidad de los aeropuertos por el simple placer de ver gigantescos aviones o r&aacute;pidos reactores volar y surcar el cielo. <\/p>\n<p>Algunos simplemente han disfrutado de esos momentos alguna vez, como de un paisaje o como una experiencia relajante. <\/p>\n<p>Otros, han querido ir m&aacute;s all&aacute; y saber, porque vuelan los aviones, a donde van y de donde vienen, porqu&eacute; llevan esas pinturas y como hablan y se entienden con el personal de tierra, de quien son y desde cuando vuelan. No son personas raras o extraordinarias, son simplemente curiosos que encuentran satisfacci&oacute;n en obtener respuestas a sus preguntas sobre la Aviaci&oacute;n. Son Spotters. <\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/www.flickr.com\/photos\/fotero\/3935102279\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2521\/3935102279_2bd9571dc7.jpg\" style=\"border:none;width:450px;height:300px\" alt=\"EC-JFF en BCN\" title=\"EC-JFF en BCN\"><\/a><\/p>\n<p>El Spotting no naci&oacute; ligado a las c&aacute;maras de fotos sino a las preguntas. Las libretas de notas vinieron despu&eacute;s y m&aacute;s tarde las c&aacute;maras de fotos. Muchos aficionados cre\u00edan que eran &#8216;raros&#8217; y que nadie m&aacute;s se dedicaba a cultivar su inusual afici&oacute;n, pero con internet encontraron otras personas apasionadas como ellos por los aviones. <\/p>\n<p>Ha sido internet lo que ha permitido que los spotters se unieran y se hicieran visibles. Una afici&oacute;n minoritaria pero enormemente social ha encontrado su cauce en la red que permite dialogar, intercambiar informaci&oacute;n, mostrar fotograf&iacute;as y admirar las de los dem&aacute;s. Y a partir de ese contacto virtual, las &#8216;quedadas&#8217; y las ca&ntilde;as, la asistencia a festivales, y un sinf&iacute;n de actividades en nada diferentes a la de cualquier otro grupo de amigos con una afici&oacute;n com&uacute;n. <\/p>\n<p>&iquest;Sientes curiosidad por la aviaci&oacute;n? A lo mejor eres un spotter y no lo sab&iacute;as. Hay un mont&oacute;n de amigos esper&aacute;ndote para compartir contigo sus conocimientos y sus ilusiones, deseando ver tus fotos o\u00edr tus historias, responder tus preguntas y saber de ti.<\/p>\n<p><strong>Repercusi\u00f3n en la red<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/aire.org\/\/index.php?option=com_content&#038;task=view&#038;id=650&#038;Itemid=1\">Aire.org<\/a> Noticias<\/li>\n<li><a href=\"http:\/\/www.elcorteingles.es\/corporativo\/cultura\/castillalamancha\/esp\/listado.asp\">Agenda Cultural<\/a> El Corte Ingl\u00e9s<\/li>\n<li><a href=\"http:\/\/avion.microsiervos.com\/fotos\/exposicion-plane-spotters-fotografiando-aviones.html\">Avi\u00f3n<\/a> Microsiervos <\/li>\n<li><a href=\"http:\/\/www.foroaviones.com\/foro\/showthread.php?t=7398\">Foroaviones<\/a><\/li>\n<li><a href=\"http:\/\/www.facebook.com\/event.php?eid=287148656802\">Facebook<\/a><\/li>\n<li><a href=\"http:\/\/www.flickr.com\/photos\/portalaire\/sets\/72157623137117307\/\">Flickr<\/a><\/li>\n<li><a href=\"http:\/\/clickair-va.com\/foros\/index.php\/topic,4882.0.html\">Clickair Virtual Airlines<\/a> Foro <\/li>\n<li><a href=\"http:\/\/twitter.com\/microsiervos\/status\/8189307841\">Twitter<\/a> (Microsiervos)<\/li>\n<li><a href=\"http:\/\/www.aviationcorner.net\/view_topic.asp?topic_id=5443\">Aviation Corner<\/a><\/li>\n<li><a href=\"http:\/\/www.noticias-aero.info\/2010\/02\/exposicion-fotografica-plane-spotters.html\">Noticias-aero<\/a><\/li>\n<li><a href=\"http:\/\/www.latribunadealbacete.es\/noticia.cfm\/Vivir\/20100204\/fenomeno\/plane\/spotters\/es\/objeto\/muestra\/corte\/ingles\/95394187-1A64-968D-594CB36995D1C73E\">La Tribuna de Albacete<\/a> 04\/02\/2010<\/li>\n<li><a href=\"http:\/\/www.latribunadealbacete.es\/noticia.cfm\/Vivir\/20100205\/plane\/spotters\/caza\/mejores\/imagenes\/aviones\/9A7BDC9B-1A64-968D-59EA86A2BE88286E\">La Tribuna de Albacete<\/a> 05\/02\/2010<\/li>\n<li><a href=\"http:\/\/blog.sandglasspatrol.com\/index.php\/noticias\/55-exhibiciones\/689-fotografia-aeronautica-en-albacete\">Sandglass Patrol<\/a><\/li>\n<li><a href=\"http:\/\/www.laverdad.es\/albacete\/v\/20100205\/sociedad_albacete\/fotografias-aviones-corte-ingles-20100205.html\">La Verdad<\/a><\/li>\n<li><a href=\"http:\/\/www.ambitocultural.es\/ambitocultural\/portal.do?IDM=7&#038;NM=2&#038;fechaInicio=05\/02\/2010&#038;fechaFinalizacion=05\/02\/2010&#038;comunidad=0\">Ambito Cultural<\/a> Espacio de Cultura de El Corte Ingl\u00e9s<\/li>\n<li>Noticias en la web del <a href=\"http:\/\/www.ejercitodelaire.mde.es\/ea\/pag?idDoc=CFDCEF2F6BA59B5FC12576C4003688B0\">Ej\u00e9rcito del Aire<\/a>.<\/li>\n<\/ul>\n<p><strong>Fotograf\u00edas de la Inauguraci\u00f3n<\/strong><\/p>\n<p style=\"text-align:center;\"><a href=\"http:\/\/www.flickr.com\/photos\/portalaire\/4332650350\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2662\/4332650350_90a3b92832_s.jpg\" style=\"border:none;width:75px;height:75px\" alt=\"el presi con los medios\" title=\"el presi con los medios\" \/><\/a>&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/portalaire\/4331912165\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2741\/4331912165_98a3c23387_s.jpg\" style=\"border:none;width:75px;height:75px\"  alt=\"descanso merecido\" title=\"descanso merecido\" \/><\/a>&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/portalaire\/4331912483\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2638\/4331912483_2b43ea7132_s.jpg\" style=\"border:none;width:75px;height:75px\" alt=\"P1150494\" title=\"P1150494\" \/><\/a>&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/portalaire\/4331914541\/\" ><img decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2762\/4331914541_53199ea0b4_s.jpg\" style=\"border:none;width:75px;height:75px\" alt=\"P1150428B\" title=\"P1150428B\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado d\u00eda 5 se inaugur\u00f3 en Albacete una exposici\u00f3n fotogr\u00e1fica organizada por la Asociaci\u00f3n Aire y patrocinada por El Corte Ingl\u00e9s y Eurocopter que pretende ofrecer una aproximaci\u00f3n al mundo de los entusiastas de la aviaci\u00f3n m\u00e1s all\u00e1 de &hellip; <a href=\"https:\/\/robertopla.net\/blog\/plane-spotters-fotografiando-aviones.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-701","post","type-post","status-publish","format-standard","hentry","category-aerotrastorno"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":0,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/701\/revisions"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}