{"id":80,"date":"2006-10-20T23:50:04","date_gmt":"2006-10-20T21:50:04","guid":{"rendered":"http:\/\/robertopla.net\/blog\/el-bar-de-makram.htm"},"modified":"2024-03-26T19:54:19","modified_gmt":"2024-03-26T18:54:19","slug":"el-bar-de-makram","status":"publish","type":"post","link":"https:\/\/robertopla.net\/blog\/el-bar-de-makram.htm","title":{"rendered":"El bar de Makram"},"content":{"rendered":"<p>Busc\u00e1bamos una taberna o similar llamada \u00abFidelio\u00bb en la que seg\u00fan el ya mencionado libro gu\u00eda serv\u00edan con acierto y a buen precio ensaladas y tablas de quesos acompa\u00f1adas de vinos. En el mismo lugar que deb\u00eda estar hab\u00eda un local con el \u00fanico letrero de \u00abviner\u00eda\u00bb sin mas indicaciones sin carta ni precios en la puerta o a la vista y para colmo, muy poco concurrido.<\/p>\n<p>No sab\u00edamos que hacer, porque los indicadores no aconsejaban entrar y a mi no me gustan los restaurantes que no tienen la carta en la puerta. Pero hab\u00edamos andado mucho y las otras opciones pasaban por cenar pizza y nosotros quer\u00edamos cenar de ensalada.<\/p>\n<p>Quedamos de acuerdo en entrar y mirar la carta y si no nos complac\u00eda, hacer como los \u00abguiris\u00bb: levantarnos e irnos. En la carta encontramos lo que busc\u00e1bamos y nos pedimos una ensalada, un plato de quesos variados y un plato de lasa\u00f1a acompa\u00f1ado de un cuarto de litro del vino de la casa. El vino de la casa era bastante corriente.<\/p>\n<p>Mientras nos tra\u00edan la cena, el mantel de papel blanco me ped\u00eda a gritos que dibujase algo. Quiz\u00e1s la inspiraci\u00f3n fue un cuadro que tenia enfrente en la pared, el caso es que empec\u00e9 a dibujar a Mercedes mientras ella me echaba una foto y segu\u00ed dibujando todo lo que la rodeaba. Al camarero, que result\u00f3 ser el propietario le hizo gracia y me cambi\u00f3 el mantel para que pudiera dibujar a gusto. Durante la cena lo fui completando y ello nos llev\u00f3 a una amena charla con Makram, que as\u00ed se llamaba el due\u00f1o del local.<\/p>\n<p>Makram es un egipcio de religi\u00f3n cristiana, tiene m\u00e1s o menos mi edad y lleg\u00f3 a Italia en los ochenta. Result\u00f3 ser un hombre muy agradable, de charla amena y car\u00e1cter afable. A pesar de la barrera del idioma conectamos bastante bien. Nos invit\u00f3 a un refrescante vino Frisanti y naturalmente le regalamos el improvisado dibujo en el mantel con una rima incluida:<\/p>\n<blockquote><p>Aqui hemos venido<br \/>\nhambrientos y cansados<br \/>\nhemos bebido vino<br \/>\ny hemos comido sano<\/p>\n<p>Si el precio lo merece,<br \/>\nvolveremos a encontrarnos<br \/>\nsiempre que a Roma vuelva<br \/>\ny tenga que repostar<\/p><\/blockquote>\n<p>No es una maravilla de m\u00e9trica y rima, pero sobre la marcha es lo que me sali\u00f3. Aunque en Espa\u00f1a es frecuente acostarse muy tarde si estas a gusto acompa\u00f1ado de los amigos y de un buen vino, pensamos que aquella gente tendr\u00eda que trabajar al d\u00eda siguiente, no como nosotros que est\u00e1bamos de vacaciones. Por otra parte, est\u00e1bamos cansados de patear Roma y al d\u00eda siguiente quer\u00edamos salir de excursi\u00f3n.<\/p>\n<p>Nos despedimos de Makram, intercambiamos la direcci\u00f3n de correo electr\u00f3nico y yo le dej\u00e9 la de \u00abmis\u00bb p\u00e1ginas web. Nos hizo prometer que volver\u00edamos a pasar antes de irnos de Roma. La direcci\u00f3n iba en una tarjeta que pusimos en el libro y se perdi\u00f3, aunque si volvimos a vernos antes de irnos de Roma. Espero que Makram lea esto y nos escriba para no perder el contacto.<\/p>\n<p><strong>MAKRAM: Noi abbiamo perso la carta con i vostri email, <a href=\"http:\/\/robertopla.net\/formmail.php\">per favore, scrivali noi<\/a><\/strong><\/p>\n<p><strong>Nota: Editado el 26\/03\/2024<\/strong> para corregir caracteres codificados err\u00f3neamente en el proceso de copias de seguridad y restauraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Busc\u00e1bamos una taberna o similar llamada \u00abFidelio\u00bb donde serv\u00edan con acierto y a buen precio ensaladas y tablas de quesos acompa\u00f1adas de vinos. <a href=\"https:\/\/robertopla.net\/blog\/el-bar-de-makram.htm\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[609,610,95,608,611],"class_list":["post-80","post","type-post","status-publish","format-standard","hentry","category-viajes","tag-bar","tag-cena","tag-dibujo","tag-roma","tag-trastevere"],"_links":{"self":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":2,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"predecessor-version":[{"id":5301,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/posts\/80\/revisions\/5301"}],"wp:attachment":[{"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertopla.net\/blog\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}